{"id":1910,"date":"2017-07-31T17:50:27","date_gmt":"2017-07-31T17:50:27","guid":{"rendered":"http:\/\/cytologystuff1.wpengine.com\/gyn-atlas-table-of-contents\/high-grade-squamous-intraepithelial-lesion\/"},"modified":"2017-11-15T07:14:38","modified_gmt":"2017-11-15T07:14:38","slug":"high-grade-squamous-intraepithelial-lesion","status":"publish","type":"page","link":"https:\/\/stage.cytologystuff.com\/de\/gyn-atlas-table-of-contents\/high-grade-squamous-intraepithelial-lesion\/","title":{"rendered":"HOCHGRADIGE PLATTENEPITHELIALE INTRAEPITHELIALE L\u00c4SIONEN (HSIL)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]PGNlbnRlcj48YSBjbGFzcz0ic2hpZnRuYXYtdG9nZ2xlIHNoaWZ0bmF2LXRvZ2dsZS1idXR0b24iIGRhdGEtc2hpZnRuYXYtdGFyZ2V0PSJzaGlmdG5hdi1tYWluIj48aSBjbGFzcz0iZmEgZmEtYmFycyI+PC9pPiBUYWJsZSBvZiBDb250ZW50cyA8L2E+PC9jZW50ZXI+[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;HOCHGRADIGE PLATTENEPITHELIALE INTRAEPITHELIALE L\u00c4SIONEN (HSIL)&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row el_id=&#8221;acknowledgements&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<br \/>\n<strong>HOCHGRADIGE PLATTENEPITHELIALE INTRAEPITHELIALE L\u00c4SIONEN (HSIL) <\/strong><br \/><em>John M. Bauer, MD<br \/>\n<\/em> <\/p>\n<p>Gew\u00f6hnlich findet man im konventionellen Pap-Abstrich, die kleinen abnormen Zellen einer HSIL, im Schleim gefangen oder versteckt zwischen Zellgruppen im Hintergrund. Proben, die mit dem ThinPrep\u00ae-System aufbereitet wurden haben eine andere Darstellung, da Schleim und Niederschlag verteilt wurden. Beim Screenen mit st\u00e4rkerer Vergr\u00f6\u00dferung treten die kleinen Zellen einer HSIL entweder einzeln, oder in kleinen Gruppen aus dem Hintergrund des Zelldeposits hervor. Diese Zellen sollten Sie veranlassen, sich das vorhandene Material genauer anzusehen und nach weiteren, diagnostisch richtungweisenden Gruppen hochgradiger Epithelien zu suchen. Immer wenn diese kleinen einzelnen Zellen oder Gruppen bei geringer Vergr\u00f6\u00dferung gesehen werden, ist es sinnvoll, einen Teil der entsprechenden Abstriche bei starker Vergr\u00f6\u00dferung zu screenen. Es ist wichtig anzumerken, dass der Dispersionsschritt des ThinPrep\u00ae-Systems echte epitheliale Zellverb\u00e4nde nicht aufbricht, dass aber aufgrund der lockeren Zellkoh\u00e4sion hochgradiger L\u00e4sionen mehr Einzelzellen vorhanden sein werden; dies sind die \u201eSchl\u00fcsselzellen\u201c, nach denen es zu suchen gilt. <\/p>\n<p><a name=\"assess\"><\/a><br \/>\nDie Kriterien f\u00fcr HSIL im ThinPrep<sup>\u00ae<\/sup> Pap Test sind wie folgt: Das wichtigste Einzelkriterium f\u00fcr eine HSIL ist das Vorhandensein asymmetrischer dreidimensionaler Strukturanomalien des Kerns. Dies ist ein Konzept, welches zur erfolgreichen Beurteilung von HSIL klar verstanden sein muss. Es gibt Strukturanomalien des dysplastischen Kerns, die nur durch Fokussieren der individuellen Zelle eindeutig eingesch\u00e4tzt werden k\u00f6nnen. Dies ist im (zweidimensionalen) Druck nur schwer zu demonstrieren; aber es ist der entscheidende Punkt. <\/p>\n<p>Stellen Sie sich bitte vor, einen Miniblumenkohl oder eine geschlossene Faust, einen Baseballhandschuh oder eine Tonsille zu fokussieren. Wie w\u00fcrde die Oberfl\u00e4che einer Traube aussehen? Ein normaler Zellkern hat eine relativ runde Form oder Eiform und seine Oberfl\u00e4che ist glatt. Eine dysplastische Zelle hat H\u00fcgel und Kurven, Riefen, Spalten und seltsame Vorspr\u00fcnge. Diese sehr ausgepr\u00e4gten Atypien sind das Malignit\u00e4tskriterium der Dysplasie, insbesondere der HSIL. Dies ist das entscheidende Detail, welches bei der konventionellen Zytologie durch die verschiedenen Artefakte bei Fixierung und F\u00e4rbung, welche die F\u00e4higkeit, diese konventionellen Abstriche zu bewerten, limitieren, am h\u00e4ufigsten verloren geht. <\/p>\n<p>Diese dreidimensionalen Strukturanomalien sind von einfachen \u201eunregelm\u00e4\u00dfigen Kernumrissen\u201c, wie sie als zweidimensionales Ph\u00e4nomen h\u00e4ufig in benignen Zellen in ThinPrep<sup>\u00ae<\/sup>Abstrichen vorkommen, zu unterscheiden. Die Zweidimensionalit\u00e4t \u00e4u\u00dfert sich dergestalt, dass diese \u201eFalten\u201c beim Fokussieren nicht in Form von Spalten und Bergen in das Zentrum des Kerns hinein verfolgt werden k\u00f6nnen etc.; sie k\u00f6nnen f\u00fcr den Anf\u00e4nger entt\u00e4uschende \u201eDifferentialdiagnosen\u201c darstellen. <\/p>\n<p>Diese dreidimensionalen Strukturanomalien m\u00fcssen nicht in jeder dysplastischen Zelle des Abstrichs vorhanden sein, aber sie werden zumindest in einigen Zellen irgendwo auf dem Pr\u00e4parat klar zu erkennen sein. Es ist offensichtlich, dass die F\u00e4higkeit \u201ein\u201c den Kern einer Zelle hineinzuschauen, direkt mit der Qualit\u00e4t der F\u00e4rbung verbunden ist. (Alle ThinPrep<sup>\u00ae<\/sup> Pr\u00e4parate erleichtern die Darstellung zellul\u00e4rer Ver\u00e4nderungen verglichen mit konventionellen Pap-Abstrichen, allerdings haben \u00dcberf\u00e4rbung oder die geringste \u00dcberalterung von Reagenzien, einen direkten Einfluss auf diesen kritischsten Aspekt der Untersuchung). Auch sollten diese dreidimensionalen Strukturanomalien asymmetrisch sein im Gegensatz zu Kernrillen oder einfachen Falten, welche die ganze Breite des Kerns betreffen und gelegentlich differentialdiagnostische Schwierigkeiten bereiten k\u00f6nnen. schaffen. Wenn diese ausgepr\u00e4gten, nukle\u00e4ren, dreidimensionalen Strukturanomalien auftreten, sind sie die Basis f\u00fcr die Diagnose einer HSIL. <\/p>\n<p style=\"padding-left:7px\"><a href=\"javascript:void(0)\"  style=\"width:350px;display:block\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/button27h.gif\" id=\"selfAssessImg\" width=\"350\" height=\"40\"><\/a><\/p>\n<div class=\"highslide-gallery\">\n<strong>Erinnerung: Sie k\u00f6nnen auf jedes Bild klicken, um dieses vergr\u00f6\u00dfert zu betrachten.<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0127.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\" name=\"pap\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0127.jpg\" alt=\"Image 1\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nDie Kerne weisen asymmetrische dreidimensionale Strukturanomalien auf (in einer zweidimensionalen Darstellung schwer nachzuvollziehen).<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>HSIL<\/strong><br \/>\nDie Kerne weisen asymmetrische dreidimensionale Strukturanomalien auf (in einer zweidimensionalen Darstellung schwer nachzuvollziehen).<br \/>\n60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0128.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0128.jpg\" alt=\"Image 2\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nDie Kernmembranen sind betont unregelm\u00e4\u00dfig und zeigen beim Fokussieren Beulen, Dellen, Spalten und Protrusionen.<br \/>\n60x<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>HSIL<\/strong><br \/>\nDie Kernmembranen sind betont unregelm\u00e4\u00dfig und zeigen beim Fokussieren Beulen, Dellen, Spalten und Protrusionen.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0134.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0134.jpg\" alt=\"Image 3\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nBetont unregelm\u00e4\u00dfige Kernmembranen und dreidimensionale Strukturunregelm\u00e4\u00dfigkeiten.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n\t<strong>HSIL<\/strong><br \/>\nBetont unregelm\u00e4\u00dfige Kernmembranen und dreidimensionale Strukturunregelm\u00e4\u00dfigkeiten.<br \/>\n60x<\/div>\n<div class=\"newRow\"><\/div>\n<p>Die Kern-Plasma-Relation ist der verl\u00e4sslichste Indikator des Schweregrades (mittel, schwer, CIS). Mit zunehmendem Schweregrad der Dysplasie, nimmt die Kern-Plasma-Relation in vorhersagbarer Weise zu. Diese abnorme Kern-Plasma-Relation kann als ein Hauptkriterium f\u00fcr die Diagnose einer HSIL angesehen werden. Jedoch gibt es einige wenige Ausnahmen, und schlie\u00dflich muss dann die Diagnose allein aufgrund von Kernver\u00e4nderungen gemacht werden. <\/p>\n<div class=\"highslide-gallery\">\n<strong>Erinnerung: Sie k\u00f6nnen auf jedes Bild klicken, um dieses vergr\u00f6\u00dfert zu betrachten.<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0129.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0129.jpg\" alt=\"Image 4\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nDie Kern-Plasma-Relation ist deutlich erh\u00f6ht und stellt den verl\u00e4sslichsten Indikator des Dysplasiegrades dar.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n\t<strong>HSIL<\/strong><br \/>\nDie Kern-Plasma-Relation ist deutlich erh\u00f6ht und stellt den verl\u00e4sslichsten Indikator des Dysplasiegrades dar.<br \/>\n<br \/> <br \/>\n60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0130.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0130.jpg\" alt=\"Image 5\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nMit zunehmendem Dysplasiegrad nimmt die Kern-Plasma-Relation in vorhersagbarer Weise zu. Dies ist ein Kernkriterium f\u00fcr die Diagnose einer HSIL.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n\t<strong>HSIL<\/strong><br \/>\nMit zunehmendem Dysplasiegrad nimmt die Kern-Plasma-Relation in vorhersagbarer Weise zu. Dies ist ein Kernkriterium f\u00fcr die Diagnose einer HSIL.<br \/>\n60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0133.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0133.jpg\" alt=\"Image 6\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nZellen einer HSIL weisen eine erh\u00f6hte Kern-Plasma-Relation auf.<br \/>\n60x<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n\t<strong>HSIL<\/strong><br \/>\nZellen einer HSIL weisen eine erh\u00f6hte Kern-Plasma-Relation auf.<br \/>\n60x<\/div>\n<\/div>\n<div class=\"newRow\"><\/div>\n<p>Es gibt zum einen die wichtigen Kernkriterien die oben beschrieben wurden (dreidimensionale Strukturanomalien des Kerns und abnorme Kernplasmarelation), die notwendig sind, um die Diagnose einer HSIL zu stellen. Dann gibt es aber noch weitere \u201eHinweise\u201c, welche h\u00e4ufig oder regelm\u00e4\u00dfig in einem Abstrich mit HSIL gefunden werden. Es sind die Folgenden: <\/p>\n<div class=\"highslide-gallery\">\n<strong>Erinnerung: Sie k\u00f6nnen auf jedes Bild klicken, um dieses vergr\u00f6\u00dfert zu betrachten.<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0131.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0131.jpg\" alt=\"Image 7\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nDie Zellen kommen h\u00e4ufig einzeln vor. Erwarten Sie keine Streifen abnormer Zellen wie man sie in den Schleimstra\u00dfen auf konventionellen Abstrichen sieht. Diese Einzelzellen k\u00f6nnen entt\u00e4uschend klein sein.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>HSIL<\/strong><br \/>\nDie Zellen kommen h\u00e4ufig einzeln vor. Erwarten Sie keine Streifen abnormer Zellen wie man sie in den Schleimstra\u00dfen auf konventionellen Abstrichen sieht. Diese Einzelzellen k\u00f6nnen entt\u00e4uschend klein sein.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0132.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0132.jpg\" alt=\"Image 8\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>HSIL<\/strong><br \/>\nDiese kleinen Einzelzellen m\u00fcssen, bei starker Vergr\u00f6\u00dferung, kritisch angesehen und nach ihren individuellen Kernmerkmalen beurteilt werden.<br \/>\n20x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>HSIL<\/strong><br \/>\nDiese kleinen Einzelzellen m\u00fcssen, bei starker Vergr\u00f6\u00dferung, kritisch angesehen und nach ihren individuellen Kernmerkmalen beurteilt werden.<br \/>\n20x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0110.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0110.jpg\" alt=\"Image 9\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nDie Zellen kommen oft in kleinen Verb\u00e4nden und kleinen Pflastersteinarrangements vor (oft etwa 4-7 Zellen). Diese Gruppen haben ein charakteristisches Erscheinungsbild und sind das Ergebnis abnormer Zellkoh\u00e4sion. Sie m\u00fcssen von \u201eSheets\u201c unterschieden werden, die wahrscheinlich nur das Ergebnis der Zugkraft des Instruments bei der Abnahme sind.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>HSIL<\/strong><br \/>\nDie Zellen kommen oft in kleinen Verb\u00e4nden und kleinen Pflastersteinarrangements vor (oft etwa 4-7 Zellen). Diese Gruppen haben ein charakteristisches Erscheinungsbild und sind das Ergebnis abnormer Zellkoh\u00e4sion. Sie m\u00fcssen von \u201eSheets\u201c unterschieden werden, die wahrscheinlich nur das Ergebnis der Zugkraft des Instruments bei der Abnahme sind.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0111.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0111.jpg\" alt=\"Image 10\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nGest\u00f6rte Kernpolarit\u00e4t. Wenn in Verb\u00e4nden, die hochgradig atypischen Kerngruppen, einen Verlust der Polarit\u00e4t oder eine chaotische Gewebearchitektur zeigen, variieren sie in Gr\u00f6\u00dfe und Form und haben wenig Respekt f\u00fcr ihre Nachbarn<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nGest\u00f6rte Kernpolarit\u00e4t. Wenn in Verb\u00e4nden, die hochgradig atypischen Kerngruppen, einen Verlust der Polarit\u00e4t oder eine chaotische Gewebearchitektur zeigen, variieren sie in Gr\u00f6\u00dfe und Form und haben wenig Respekt f\u00fcr ihre Nachbarn<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0112.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0112.jpg\" alt=\"Image 11\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nVorkommen von \u201eNacktkernen\u201c. Wenn diese auch manchmal in benignen (besonders atrophischen) Abstrichen gefunden werden, sollten sie doch nie ignoriert werden. Sie sind ein sehr verl\u00e4sslicher Indikator einer HSIL.<br \/>\n40x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nVorkommen von \u201eNacktkernen\u201c. Wenn diese auch manchmal in benignen (besonders atrophischen) Abstrichen gefunden werden, sollten sie doch nie ignoriert werden. Sie sind ein sehr verl\u00e4sslicher Indikator einer HSIL.<br \/>\n40x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0114.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0114.jpg\" alt=\"Image 12\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nDie gleichzeitige Anwesenheit von eindeutigeren LSIL-Zellen. Das Konzept der Progression von LSIL zu HSIL wird etwas kontrovers gesehen. Auch wenn die gr\u00f6\u00dferen, leichter erkennbaren Zellen einer LSIL h\u00e4ufig gesehen werden ist dies keineswegs ein konsistentes Merkmal.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nDie gleichzeitige Anwesenheit von eindeutigeren LSIL-Zellen. Das Konzept der Progression von LSIL zu HSIL wird etwas kontrovers gesehen. Auch wenn die gr\u00f6\u00dferen, leichter erkennbaren Zellen einer LSIL h\u00e4ufig gesehen werden ist dies keineswegs ein konsistentes Merkmal.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0116.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0116.jpg\" alt=\"Image 13\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nUnregelm\u00e4\u00dfigkeit der Kerngr\u00f6\u00dfe alleine ist ein viel weniger verl\u00e4sslicher Indikator einer Dysplasie.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nUnregelm\u00e4\u00dfigkeit der Kerngr\u00f6\u00dfe alleine ist ein viel weniger verl\u00e4sslicher Indikator einer Dysplasie.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0117.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0117.jpg\" alt=\"Image 14\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nEine Variation der Kerngr\u00f6\u00dfe ist nur von Bedeutung, wenn sie zusammen mit dreidimensionalen Strukturanomalien des Kerns vorkommt.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nEine Variation der Kerngr\u00f6\u00dfe ist nur von Bedeutung, wenn sie zusammen mit dreidimensionalen Strukturanomalien des Kerns vorkommt.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0118.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0118.jpg\" alt=\"Image 15\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nHyperchromasie. N\u00fctzlich falls vorhanden, was jedoch nicht immer der Fall ist.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nHyperchromasie. N\u00fctzlich falls vorhanden, was jedoch nicht immer der Fall ist.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0120.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0120.jpg\" alt=\"Image 16\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nChromatinverklumpung oder -k\u00f6rnigkeit. Ein n\u00fctzliches \u201eMalignit\u00e4tskriterium\u201c, wenn es zusammen mit dreidimsionalen Deformit\u00e4ten und abnormer Kernplasmarelation gesehen wird. Alleine jedoch selten aussagekr\u00e4ftig.<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nChromatinverklumpung oder -k\u00f6rnigkeit. Ein n\u00fctzliches \u201eMalignit\u00e4tskriterium\u201c, wenn es zusammen mit dreidimsionalen Deformit\u00e4ten und abnormer Kernplasmarelation gesehen wird. Alleine jedoch selten aussagekr\u00e4ftig.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0122.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0122.jpg\" alt=\"Image 17\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>HSIL<\/strong><br \/>\nNukleoli sind im Allgemeinen unverd\u00e4chtig oder fehlen. Nukleoli k\u00f6nnen vorhanden sein, wenn gleichzeitig ein entz\u00fcndlicher\/reaktiver Prozess oder eine Beteiligung des Dr\u00fcsengewebes vorliegt<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>HSIL<\/strong><br \/>\nNukleoli sind im Allgemeinen unverd\u00e4chtig oder fehlen. Nukleoli k\u00f6nnen vorhanden sein, wenn gleichzeitig ein entz\u00fcndlicher\/reaktiver Prozess oder eine Beteiligung des Dr\u00fcsengewebes vorliegt<br \/>\n60x\n<\/div>\n<\/div>\n<div class=\"newRow\"><\/div>\n<p>Wenn diese \u201eSchl\u00fcsselkriterien\u201c entdeckt werden, sollte eine sorgf\u00e4ltige Suche nach den diagnoseweisenden Zellen mit unzweifelhaften, klaren Atypien der Kernstruktur einsetzen. Nur wenn diese Zellen gefunden werden, kann die Diagnose einer HSIL mit gutem Gewissen gestellt werden. <\/p>\n<p>Eine Metaplasie sollte stets als ein von einer Dysplasie unabh\u00e4ngiges Ph\u00e4nomen betrachtet werden. Wenn eine Dysplasie in Gegenwart einer Metaplasie auftritt, muss eine &#8220;Korrektur&#8221; bez\u00fcglich der Bewertung der Kern-Plasma-Relationen vorgenommen werden. Wir beginnen theoretisch mit einer Zelle, die, aufgrund einer Metaplasie bereits eine abnorme Kern-Plasma-Relation hat. Diese Zelle wird daher weniger hilfreich sein, den Grad einer Dysplasie zu bestimmen. Lassen Sie sich von der Kernplasmarelation bei Vorliegen einer Metaplasie nicht t\u00e4uschen. <\/p>\n<p>Eine Dr\u00fcsenzellbeteiligung bei HSIL hat im ThinPrep\u00ae Pap Test ein eindeutiges Erscheinungsbild und kann von L\u00e4sionen dr\u00fcsigen Ursprungs unterschieden werden. SIL in Dr\u00fcsen zeigt sich vorwiegend in Sheets mit gr\u00f6\u00dferer Raumtiefe. Das Zytoplasma ist fein vakuolisiert, was zun\u00e4chst den Eindruck eines glandul\u00e4ren Prozesses hervorrufen mag. Bei genauerer Betrachtung zeigen diese Zellverb\u00e4nde jedoch keine Zeichen dr\u00fcsiger Differenzierung wie, basale Kerne, dichte Formationen von Zylinderzellen, Pseudostratifizierung, ausgefiederte R\u00e4nder oder Rosetten. Diese Zellverb\u00e4nde k\u00f6nnen t\u00e4uschend flach sein, aber die Kerne weisen dieselben Kriterien einer SIL auf, die oben beschrieben wurden. Da diese Zellen in sheets vorkommen und in der Regel klein sind, keine anderen Kriterien zur HSIL-Diagnose als diskrete, dreidimensionale Deformit\u00e4ten- k\u00f6nnen sie am Schwierigsten zu entdecken und zu bewerten sein. Eine wichtige Hilfe, festzustellen, ob diese Zellen plattenepithelialer oder dr\u00fcsiger Herkunft sind, ist die Gesellschaft, in der sie sich befinden. Denken Sie an die \u201egleich und gleich gesellt sich gern\u201c- Regel. In den meisten F\u00e4llen werden diese Zellen von eindeutig dysplastischen Plattenepithelien begleitet sein. <\/p>\n<div class=\"highslide-gallery\">\n<strong>Erinnerung: Sie k\u00f6nnen auf jedes Bild klicken, um dieses vergr\u00f6\u00dfert zu betrachten.<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0123.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0123.jpg\" alt=\"Image 18\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>Look-Alike<\/strong><br \/>\nHSIL mit Dr\u00fcsenzellbeteiligung 40x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>Look-Alike<\/strong><br \/>\nHSIL mit Dr\u00fcsenzellbeteiligung 40x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0124.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0124.jpg\" alt=\"Image 19\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>Look-Alike<\/strong><br \/>\nHSIL 60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>Look-Alike<\/strong><br \/>\nHSIL 60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0125.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0125.jpg\" alt=\"Image 20\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>Look-Alike<\/strong><br \/>\nAtrophie 60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        <strong>Look-Alike<\/strong><br \/>\nAtrophie 60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide0126.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide0126.jpg\" alt=\"Image 21\" border=\"0\" title=\"Click to enlarge\"><\/a><\/p>\n<div class=\"highslide-caption\">\n\t<strong>Look-Alike<\/strong><br \/>\nEndometriumzellen 60x\n<\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>Look-Alike<\/strong><br \/>\nEndometriumzellen 60x\n<\/div>\n<\/div>\n<div class=\"newRow\"><\/div>\n<p><a name=\"readings\"><\/a><strong>LITERATUR:<\/strong><\/p>\n<ol class=\"normal\">\n<li>Baker JJ: Conventional and liquid-based cervicovaginal cytology: A comparison study with clinical and histologic follow-up. Diagn Cytopathol 2002;27(3):185-88.\n <\/li>\n<li>Bernstein SJ et al: Liquid-based cervical cytologic smear study and conventional Papanicolaou smears: A metaanalysis of prospective studies comparing cytologic diagnosis and sample adequacy. Am J Obstet Gyenecol 2001; 185:308-17.\n <\/li>\n<li>Diaz-Rosario LA, Kabawat SE: Performance of a fluid-based, thin-layer Papanicolaou smear method in the clinical setting of an independent laboratory and an outpatient screening population in New England. Arch Pathol Lab Med 1999: 123(9):817-21.\n <\/li>\n<li>Selvaggi SM: Cytologic features of high-grade squamous lesions involving endocervical glands on ThinPrep cytology. Diagn Cytopathol 2002;26(3):181-85.\n<\/li>\n<li>Weintraub J, Morabia A: Efficacy of a liquid-based thin layer method for cervical cancer screening in a population with a low incidence of cervical cancer. Diagn Cytopathol 200;22(1):52-9.\n <\/li>\n<li>Hologic, Inc. ThinPrep<sup>\u00ae<\/sup> 2000 System Package Insert 2001.\n<\/li>\n<\/ol>\n<p><a href=\"#top\">Zur\u00fcck nach oben<\/a><\/p>\n<\/div>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1500390293825{margin-top: 30px !important;}&#8221; el_class=&#8221;back-to-top&#8221;]<strong><a href=\"#main\">Back to Top<\/a><\/strong>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_widget_sidebar sidebar_id=&#8221;consulting-right-sidebar&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]PGNlbnRlcj48YSBjbGFzcz0ic2hpZnRuYXYtdG9nZ2xlIHNoaWZ0bmF2LXRvZ2dsZS1idXR0b24iIGRhdGEtc2hpZnRuYXYtdGFyZ2V0PSJzaGlmdG5hdi1tYWluIj48aSBjbGFzcz0iZmEgZmEtYmFycyI+PC9pPiBUYWJsZSBvZiBDb250ZW50cyA8L2E+PC9jZW50ZXI+[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;HOCHGRADIGE PLATTENEPITHELIALE INTRAEPITHELIALE L\u00c4SIONEN (HSIL)&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row el_id=&#8221;acknowledgements&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_column_text] HOCHGRADIGE PLATTENEPITHELIALE INTRAEPITHELIALE L\u00c4SIONEN (HSIL) John M. Bauer, MD Gew\u00f6hnlich findet man im konventionellen Pap-Abstrich, die kleinen abnormen Zellen einer HSIL, im Schleim gefangen oder versteckt zwischen Zellgruppen im Hintergrund. Proben, die mit dem ThinPrep\u00ae-System aufbereitet wurden haben eine andere<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":1889,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-1910","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/pages\/1910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/comments?post=1910"}],"version-history":[{"count":0,"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/pages\/1910\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/pages\/1889"}],"wp:attachment":[{"href":"https:\/\/stage.cytologystuff.com\/de\/wp-json\/wp\/v2\/media?parent=1910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}