{"id":2056,"date":"2017-08-01T13:26:46","date_gmt":"2017-08-01T13:26:46","guid":{"rendered":"http:\/\/cytologystuff1.wpengine.com\/non-gyn-atlas\/fine-needle-aspiration-cytology-thyroid\/"},"modified":"2017-11-22T11:03:14","modified_gmt":"2017-11-22T11:03:14","slug":"fine-needle-aspiration-cytology-thyroid","status":"publish","type":"page","link":"https:\/\/stage.cytologystuff.com\/fr\/non-gyn-atlas\/fine-needle-aspiration-cytology-thyroid\/","title":{"rendered":"Cytoponction \u00e0 l&#8217;aiguille fine"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]PGNlbnRlcj48YSBjbGFzcz0ic2hpZnRuYXYtdG9nZ2xlIHNoaWZ0bmF2LXRvZ2dsZS1idXR0b24iIGRhdGEtc2hpZnRuYXYtdGFyZ2V0PSJzaGlmdG5hdi1tYWluIj48aSBjbGFzcz0iZmEgZmEtYmFycyI+PC9pPiBUYWJsZSBvZiBDb250ZW50cyA8L2E+PC9jZW50ZXI+[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;Cytoponction \u00e0 l&#8217;aiguille fine&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<div id=>\n<p class=\"subhead\">Thyro\u00efde<br \/>\n         <em>Helen H. Wang, MD, DrPH<br \/>\n  <\/em> <\/p>\n<p><strong>Introduction<\/strong><\/p>\n<p>Les nodules thyro\u00efdiens font partie des d\u00e9couvertes cliniques courantes, avec un taux annuel d&#8217;incidence estim\u00e9 \u00e0 4-8 %. <sup>[1] <\/sup>On estime qu&#8217;entre 10 et 20 millions d&#8217;Am\u00e9ricains souffrent de nodules thyro\u00efdiens cliniquement d\u00e9tectables. <sup>[1]<\/sup> Comme il s&#8217;agit d&#8217;une technique s\u00fbre, \u00e9conomique et permettant une s\u00e9lection optimale des patients qui doivent subir une intervention, la cytoponction thyro\u00efdienne \u00e0 l&#8217;aiguille fine repr\u00e9sente le test initial de prise en charge de la plupart des patients pr\u00e9sentant un nodule thyro\u00efdien. <sup>[2]<\/sup> Il n&#8217;est donc pas \u00e9tonnant que le type d&#8217;\u00e9chantillons le plus couramment trouv\u00e9 dans un laboratoire soit pr\u00e9lev\u00e9 par cytoponction thyro\u00efdienne. Pourtant, malgr\u00e9 une large adoption depuis les ann\u00e9es 1970, le traitement et les r\u00e9sultats de cet examen sont toujours controvers\u00e9s.<\/p>\n<p><strong>Recueil et traitement des \u00e9chantillons<\/strong><br \/>\nLa cytoponction thyro\u00efdienne \u00e0 l&#8217;aiguille fine est r\u00e9alis\u00e9e par palpation ou sous guidage \u00e9chographique, selon la taille de la l\u00e9sion. Le traitement est identique dans les deux cas, c&#8217;est-\u00e0-dire que le pr\u00e9l\u00e8vement est directement \u00e9tal\u00e9 sur des lames (m\u00e9thode conventionnelle) ou rinc\u00e9 dans une solution de conservation pour une pr\u00e9paration en milieu liquide. Deux \u00e9tudes comparant les pr\u00e9parations ThinPrep<sup>\u00ae<\/sup> aux frottis conventionnels accordent aux deux m\u00e9thodes une pr\u00e9cision comparable dans la d\u00e9tection des n\u00e9oplasmes thyro\u00efdiens. <sup>[3, 4]<\/sup> Une de ces \u00e9tudes a pourtant montr\u00e9 que les pr\u00e9parations ThinPrep pr\u00e9sentent une corr\u00e9lation globale inf\u00e9rieure avec le diagnostic histologique par rapport aux frottis directs, en particulier dans la d\u00e9tection de la thyro\u00efdite lympho\u00efde chronique (62 % pour ThinPrep contre 92 % pour les frottis directs). <sup>[4]<\/sup> En outre, certains auteurs ont sugg\u00e9r\u00e9 que les pr\u00e9parations ThinPrep ne permettent pas de d\u00e9tecter les collo\u00efdes s\u00e9reux ou diffus. <sup>[3, 5]<\/sup> Dans une \u00e9tude conduite par Tulecke, et al., le &#8220;mat\u00e9riel \u00e0 l&#8217;aspect de papier&#8221; observ\u00e9 sur les lames ThinPrep s&#8217;est av\u00e9r\u00e9 associ\u00e9 \u00e0 une quantit\u00e9 abondante de collo\u00efde lors de l&#8217;examen histologique et repr\u00e9sente probablement un collo\u00efde s\u00e9reux. <sup>[6]<\/sup> Dans l&#8217;ensemble, les pr\u00e9parations ThinPrep semblent contenir une quantit\u00e9 inf\u00e9rieure de collo\u00efdes que les frottis conventionnels. En revanche, la m\u00e9thode ThinPrep permet une meilleure visualisation des caract\u00e9ristiques nucl\u00e9aires essentielles au diagnostic de carcinome papillaire. Elle semble en outre briser les follicules et pr\u00e9senter plus facilement des cellules folliculaires dans des amas, groupes ou m\u00eame sous forme isol\u00e9e.<\/p>\n<p><strong>Classification<\/strong><br \/>\nDe nombreuses classifications ont \u00e9t\u00e9 propos\u00e9es et employ\u00e9es dans la litt\u00e9rature. Nous en avons trouv\u00e9 une qui sera aussi utile aux pathologistes qu&#8217;aux cliniciens, car elle est bas\u00e9e sur la probabilit\u00e9 de d\u00e9tecter un carcinome \u00e0 l&#8217;aide des r\u00e9sultats histologiques. <\/p>\n<p><strong>Tumeur maligne<\/strong><br \/>\nLes \u00e9chantillons class\u00e9s dans cette cat\u00e9gorie repr\u00e9sentent les cas dans lesquels la r\u00e9section permet quasiment toujours d&#8217;\u00e9tablir un diagnostic de tumeur maligne. Le carcinome papillaire (tumeur maligne la plus courante pour la thyro\u00efde) poss\u00e8de des caract\u00e9ristiques nucl\u00e9aires sp\u00e9cifiques facilement identifiables sur les \u00e9chantillons cytologiques. Parmi les autres tumeurs malignes pouvant \u00eatre pr\u00e9cis\u00e9ment diagnostiqu\u00e9es gr\u00e2ce \u00e0 la cytologie, citons les carcinomes m\u00e9dullaires, lymphomes et carcinomes m\u00e9tastatiques. Sur les lames ThinPrep, le carcinome papillaire est caract\u00e9ris\u00e9 par des amas et groupes papillaires de cellules encombr\u00e9es avec hypertrophie et moulage nucl\u00e9aires, chromatine poudreuse, membranes nucl\u00e9aires irr\u00e9guli\u00e8res (marqu\u00e9es par des fentes nucl\u00e9aires et des inclusions cytoplasmiques intranucl\u00e9aires) et des nucl\u00e9oles petits mais pro\u00e9minents et souvent \u00e9osinophiles. <sup>[7]<\/sup> \u00c0 l&#8217;inverse, le carcinome m\u00e9dullaire est caract\u00e9ris\u00e9 par des cellules plasmacyto\u00efdes monomorphes isol\u00e9es pr\u00e9sentant un rapport nucl\u00e9o\/cytoplasmique \u00e9lev\u00e9, des noyaux excentr\u00e9s et une chromatine grossi\u00e8rement granulaire avec ou sans nucl\u00e9ole pro\u00e9minent. De petits granules discrets remplissent le cytoplasme. Les cellules paraissent occasionnellement fusel\u00e9es ; en revanche toutes pr\u00e9sentent les m\u00eames caract\u00e9ristiques nucl\u00e9aires. Les lymphomes et carcinomes m\u00e9tastatiques de la thyro\u00efde sont beaucoup moins courants. Leurs caract\u00e9ristiques cytologiques d\u00e9pendent respectivement de leur type et du site d&#8217;origine. <\/p>\n<p><strong>Suspicion de tumeur maligne<\/strong><br \/>\nQuand l&#8217;\u00e9chantillon n&#8217;est pas hypercellulaire et pr\u00e9sente la majorit\u00e9 (mais pas toutes) des caract\u00e9ristiques du carcinome papillaire et m\u00e9dullaire ou d&#8217;une autre tumeur maligne (voir ci-dessus), on le classe dans la cat\u00e9gorie &#8220;Suspicion de tumeur maligne&#8221;. Dans la litt\u00e9rature, la valeur pr\u00e9dictive positive (taux de tumeurs malignes diagnostiqu\u00e9es \u00e0 partir des r\u00e9sultats histologiques) de la cat\u00e9gorie &#8220;Suspicion de carcinome papillaire&#8221; oscille entre 54 et 84 %, selon que le mod\u00e8le de classification contient ou pas une autre cat\u00e9gorie de diagnostic non d\u00e9finitif (par exemple, &#8220;R\u00e9sultat ind\u00e9termin\u00e9&#8221;). <sup>[7, 8, 9, 10]<\/sup> Ainsi, quand la classification comporte une cat\u00e9gorie &#8220;R\u00e9sultat ind\u00e9termin\u00e9&#8221; et &#8220;Suspicion de&#8221;, la VPP de cette seconde cat\u00e9gorie est de 64 % ou plus. <sup>[7, 9, 10]<\/sup> Comme les autres types de carcinome de la thyro\u00efde sont beaucoup moins courants, nous ne connaissons pas leur VPP en relation avec un diagnostic de suspicion. <\/p>\n<p><strong>R\u00e9sultat ind\u00e9termin\u00e9 de tumeur maligne<\/strong> <br \/>\nDans notre laboratoire, cette cat\u00e9gorie inclut les \u00e9chantillons dont les r\u00e9sultats histologiques permettent d&#8217;\u00e9tablir une valeur pr\u00e9dictive de tumeur maligne inf\u00e9rieure \u00e0 50 % (dans la plupart des cas inf\u00e9rieure \u00e0 30 %) et sup\u00e9rieure \u00e0 10 %. <sup>[6, 7]<\/sup> On y trouve donc les \u00e9chantillons qui affichent quelques caract\u00e9ristiques du carcinoma papillaire, mais pas suffisamment pour les classer dans la cat\u00e9gorie &#8220;Suspicion de&#8221;. <sup>[7]<\/sup> Dans la litt\u00e9rature, sa valeur pr\u00e9dictive positive se situe entre 20 et 54 %. <sup>[7, 9, 10, 11]<\/sup> Ces l\u00e9sions repr\u00e9sentent souvent la variante folliculaire du carcinome papillaire. Cette cat\u00e9gorie diagnostique inclut \u00e9galement les n\u00e9oplasmes folliculaires et \u00e0 cellules de H\u00fcrthle, caract\u00e9ris\u00e9s par des collo\u00efdes et cellules folliculaires rares si\u00e9geant dans des microfollicules, des groupes encombr\u00e9s ou sous forme de cellules de H\u00fcrthle isol\u00e9es. Dans la litt\u00e9rature, la valeur pr\u00e9dictive positive d&#8217;un carcinome pour ces l\u00e9sions varie de 2 \u00e0 91 %, <sup>[6, 9, 10, 12, 13, 14, 15, 16, 17, 18, 19, 20, 21, 22, 23, 24, 25, 26, 27]<\/sup> l&#8217;\u00e9cart \u00e9tant probablement d\u00fb \u00e0 des d\u00e9finitions diff\u00e9rentes de ces termes et \u00e0 des crit\u00e8res variables de classification\/diagnostic histologique. Cette valeur est, \u00e0 quelques exceptions pr\u00e8s, en majorit\u00e9 inf\u00e9rieure \u00e0 30 %. <sup>[10, 15, 22, 24, 27]<\/sup><\/p>\n<p><strong>L\u00e9sion tr\u00e8s probablement b\u00e9nigne<br \/><\/strong><br \/>\nCette cat\u00e9gorie inclut les l\u00e9sions folliculaires affichant une morphologie macrofolliculaire ou mixte (micro et macrofolliculaire) avec quantit\u00e9 abondante de collo\u00efdes dans le fond. Sur les lames ThinPrep, les macrofollicules apparaissent dans des amas de douzaines de cellules r\u00e9guli\u00e8rement espac\u00e9es avec une bonne distance entre les noyaux. Sur ces lames, la signification des cellules folliculaires isol\u00e9es est incertaine car elles sont observ\u00e9es dans une morphologie par ailleurs micro ou macrofolliculaire. Comme la probabilit\u00e9 que les r\u00e9sultats histologiques de ces l\u00e9sions permettent de les classer comme tumeur maligne (variante folliculaire du carcinome papillaire ou carcinome folliculaire) est faible mais pas nulle (de 0 \u00e0 43 % dans la litt\u00e9rature) <sup>[6, 9, 12, 13, 14, 15, 16, 17, 18, 19, 20, 21, 24, 25, 26, 27]<\/sup> avec seulement trois cas <sup>[14, 16, 27]<\/sup> sup\u00e9rieurs \u00e0 6 %, nous les classons dans la cat\u00e9gorie &#8220;L\u00e9sion tr\u00e8s probablement b\u00e9nigne&#8221; plut\u00f4t que &#8220;Diagnostic sans \u00e9quivoque de l\u00e9sion b\u00e9nigne&#8221;. <\/p>\n<p><strong>Absence de cellules malignes concordant avec une thyro\u00efdite de Hashimoto<\/strong><br \/>\nNous nous sommes rendus compte que la m\u00e9thode ThinPrep ne permet pas d&#8217;\u00e9tablir un diagnostic optimal de thyro\u00efdite. <sup>[6]<\/sup> La thyro\u00efdite de Hashimoto est caract\u00e9ris\u00e9e par des amas ou groupes de cellules folliculaires pr\u00e9sentant divers degr\u00e9s d&#8217;apparition de cellules de H\u00fcrthle dans un fond contenant un nombre variable de lymphocytes et de cellules plasmatiques avec des agr\u00e9gats lympho\u00efdes et folliculaires centraux occasionnels. Comme la thyro\u00efdite lympho\u00efde\/de Hashimoto est une pathologie courante de la thyro\u00efde, la qualit\u00e9 de l&#8217;\u00e9chantillon est cruciale pour pouvoir \u00e9carter d&#8217;autres l\u00e9sions coexistantes plus significatives. <\/p>\n<p><strong>Cellularit\u00e9 non optimale mais caract\u00e9ristiques sugg\u00e9rant<\/strong><br \/>\nDans la mesure o\u00f9 la cytoponction thyro\u00efdienne \u00e0 l&#8217;aiguille fine sert essentiellement \u00e0 orienter les patients vers une intervention chirurgicale ou un suivi, nous objectif consiste \u00e0 obtenir une cellularit\u00e9 plus qu&#8217;ad\u00e9quate permettant d&#8217;\u00e9tablir un diagnostic d\u00e9finitif. Si la cellularit\u00e9 n&#8217;est pas optimale (mais suffisante pour sugg\u00e9rer un diagnostic), nous commen\u00e7ons par classer l&#8217;\u00e9chantillon dans cette cat\u00e9gorie, puis nous le classons ensuite dans l&#8217;une des cat\u00e9gories ci-dessus. Cette cat\u00e9gorie inclut les \u00e9chantillons avec contenu kystique (macrophages) et tr\u00e8s peu de cellules folliculaires. Nous ne disposons d&#8217;aucun seuil quantitatif pour cette cat\u00e9gorie, mais nous nous appuyons sur une combinaison de caract\u00e9ristiques (dont la quantit\u00e9 de collo\u00efdes et la disposition cellulaire) et de caract\u00e9ristiques cytologiques pour prendre cette d\u00e9cision. <\/p>\n<p><strong>\u00c9l\u00e9ments non diagnostiques<\/strong><br \/>\nCette cat\u00e9gorie est g\u00e9n\u00e9ralement r\u00e9serv\u00e9e aux \u00e9chantillons qui ne contiennent quasiment aucune cellule folliculaire (ou tr\u00e8s peu).<\/p>\n<p><strong>R\u00e9f\u00e9rences<\/strong> <\/p>\n<ol class=\"normal\">\n<li>Cramer H. Fine-needle aspiration cytology of the thyroid: an appraisal. Cancer 2000; 90(6):325-9.<\/li>\n<li>Mazzaferri EL. Management of a solitary thyroid nodule [see comments]. N Engl J Med 1993; 328(8):553-9. <\/li>\n<li>Biscotti CV, Hollow JA, Toddy SM, Easley KA. ThinPrep versus conventional smear cytologic preparations in the analysis of thyroid fine-needle aspiration specimens. Am J Clin Pathol 1995; 104(2):150-3. <\/li>\n<li>Frost AR, Sidawy MK, Ferfelli M, et al. Utility of thin-layer preparations in thyroid fine-needle aspiration: diagnostic accuracy, cytomorphology, and optimal sample preparation. Cancer 1998; 84(1):17-25. <\/li>\n<li>Afify AM, Liu J, Al-Khafaji BM. Cytologic artifacts and pitfalls of thyroid fine-needle aspiration using ThinPrep: a comparative retrospective review. Cancer 2001; 93(3):179-86. <\/li>\n<li>Tulecke MA, Wang HH. ThinPrep for cytologic evaluation of follicular thyroid lesions: correlation with histologic findings. Diagn Cytopathol 2004; 30(1):7-13. <\/li>\n<li>Zhang Y, Fraser JL, Wang HH. Morphologic predictors of papillary carcinoma on fine-needle aspiration of thyroid with ThinPrep preparations. Diagn Cytopathol 2001; 24(6):378-83. <\/li>\n<li>Chen H, Zeiger MA, Clark DP, Westra WH, Udelsman R. Papillary carcinoma of the thyroid: can operative management be based solely on fine-needle aspiration? J Am Coll Surg 1997; 184(6):605-10. <\/li>\n<li>Renshaw AA. Accuracy of thyroid fine-needle aspiration using receiver operator characteristic curves. Am J Clin Pathol 2001; 116(4):477-82. <\/li>\n<li>Goldstein RE, Netterville JL, Burkey B, Johnson JE. Implications of follicular neoplasms, atypia, and lesions suspicious for malignancy diagnosed by fine-needle aspiration of thyroid nodules. Ann Surg 2002; 235(5):656-62; discussion 662-4. <\/li>\n<li>Renshaw AA. Focal features of papillary carcinoma of the thyroid in fine-needle aspiration material are strongly associated with papillary carcinoma at resection. Am J Clin Pathol 2002; 118(2):208-10. <\/li>\n<li>Al-Rikabi AC, Al-Omran M, Cheema M, El-Khwsky F, Al-Nuaim A. Pattern of thyroid lesions and role of fine needle aspiration cytology (FNA) in the management of thyroid enlargement: a retrospective study from a teaching hospital in Riyadh. Apmis 1998; 106(11):1069-74. <\/li>\n<li>Baloch ZW, Tam D, Langer J, Mandel S, LiVolsi VA, Gupta PK. Ultrasound-guided fine-needle aspiration biopsy of the thyroid: role of on-site assessment and multiple cytologic preparations. Diagn Cytopathol 2000; 23(6):425-9. <\/li>\n<li>Boyd LA, Earnhardt RC, Dunn JT, Frierson HF, Hanks JB. Preoperative evaluation and predictive value of fine-needle aspiration and frozen section of thyroid nodules. J Am Coll Surg 1998; 187(5):494-502. <\/li>\n<li>Hawkins F, Bellido D, Bernal C, et al. Fine needle aspiration biopsy in the diagnosis of thyroid cancer and thyroid disease. Cancer 1987; 59(6):1206-9. <\/li>\n<li>Ko HM, Jhu IK, Yang SH, et al. Clinicopathologic analysis of fine needle aspiration cytology of the thyroid. A review of 1,613 cases and correlation with histopathologic diagnoses. Acta Cytol 2003; 47(5):727-32. <\/li>\n<li>Mandreker SR, Nadkarni NS, Pinto RG, Menezes S. Role of fine needle aspiration cytology as the initial modality in the investigation of thyroid lesions. Acta Cytol 1995; 39(5):898-904. <\/li>\n<li>Miller JM, Kini SR, Hamburger JI. The diagnosis of malignant follicular neoplasms of the thyroid by needle biopsy. Cancer 1985; 55(12):2812-7. <\/li>\n<li>Morgan JL, Serpell JW, Cheng MS. Fine-needle aspiration cytology of thyroid nodules: how useful is it? ANZ J Surg 2003; 73(7):480-3. <\/li>\n<li>Prinz RA, O&#8217;Morchoe PJ, Barbato AL, et al. Fine needle aspiration biopsy of thyroid nodules. Ann Surg 1983; 198(1):70-3. <\/li>\n<li>Ravetto C, Colombo L, Dottorini ME. Usefulness of fine-needle aspiration in the diagnosis of thyroid carcinoma: a retrospective study in 37,895 patients. Cancer 2000; 90(6):357-63. <\/li>\n<li>Nam-Goong IS, Kim HY, Gong G, et al. Ultrasonography-guided fine-needle aspiration of thyroid incidentaloma: correlation with pathological findings. Clin Endocrinol (Oxf) 2004; 60(1):21-8. <\/li>\n<li>Silverman JF, West RL, Larkin EW, et al. The role of fine-needle aspiration biopsy in the rapid diagnosis and management of thyroid neoplasm. Cancer 1986; 57(6):1164-70. <\/li>\n<li>La Rosa GL, Belfiore A, Giuffrida D, et al. Evaluation of the fine needle aspiration biopsy in the preoperative selection of cold thyroid nodules. Cancer 1991; 67(8):2137-41. <\/li>\n<li>DeMay RM. Follicular lesions of the thyroid. W(h)ither follicular carcinoma? Am J Clin Pathol 2000; 114(5):681-3. <\/li>\n<li>Mate\u00c5\u00a1a N, Tabain I, Dabelic N, Petric V, Kusic Z. Diagnostic relevance of fine needle aspiration cytology for follicular lesions of the thyroid: retrospective study. Croat Med J 2002; 43(5):606-9. <\/li>\n<li>Blansfield JA, Sack MJ, Kukora JS. Recent experience with preoperative fine-needle aspiration biopsy of thyroid nodules in a community hospital. Arch Surg 2002; 137(7):818-21. <\/li>\n<\/ol>\n<p style=\"padding-left:7px\"><a href=\"javascript:void(0)\"  style=\"width:350px;display:block\"><img loading=\"lazy\" decoding=\"async\" src=\"\/images\/button27h.gif\" id=\"selfAssessImg\" width=\"350\" height=\"40\"><\/a><\/p>\n<p><strong><em>Diagnostic positif de carcinome papillaire<\/em><\/strong><\/p>\n<div class=\"highslide-gallery\">\n<strong>Rappel : Vous pouvez cliquer sur une image<br \/>\nde l&#8217;Atlas pour la voir dans un format plus grand.<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1001.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1001.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 1<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nL&#8217;hypercellularit\u00e9 avec pr\u00e9sence de nombreux amas et groupes coh\u00e9sifs de cellules folliculaires observ\u00e9s \u00e0 faible grossissement (comme sur cette image) constituent le premier crit\u00e8re d&#8217;\u00e9tablissement d&#8217;un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n10x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 1<br \/>\n        \t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nL&#8217;hypercellularit\u00e9 avec pr\u00e9sence de nombreux amas et groupes coh\u00e9sifs de cellules folliculaires observ\u00e9s \u00e0 faible grossissement (comme sur cette image) constituent le premier crit\u00e8re d&#8217;\u00e9tablissement d&#8217;un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n10x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1002.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1002.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 2<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nLa pr\u00e9sence d&#8217;une architecture papillaire telle que celle visible sur cette image n&#8217;est pas obligatoire pour \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n20X <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 2<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nLa pr\u00e9sence d&#8217;une architecture papillaire telle que celle visible sur cette image n&#8217;est pas obligatoire pour \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n20X <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1003.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1003.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 3<br \/>\n<\/strong><br \/>\nCarcinome papillaire.<br \/>\nSur les pr\u00e9parations ThinPrep, les carcinomes papillaires se pr\u00e9sentent souvent sous la forme d&#8217;amas de cellules folliculaires augment\u00e9es en taille avec membranes nucl\u00e9aires irr\u00e9guli\u00e8res et petits nucl\u00e9oles (mais pro\u00e9minents) et souvent \u00e9osinophiles.<br \/>\n60X <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n<strong>Figure 3<br \/>\n<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nSur les pr\u00e9parations ThinPrep, les carcinomes papillaires se pr\u00e9sentent souvent sous la forme d&#8217;amas de cellules folliculaires augment\u00e9es en taille avec membranes nucl\u00e9aires irr\u00e9guli\u00e8res et petits nucl\u00e9oles (mais pro\u00e9minents) et souvent \u00e9osinophiles.<br \/>\n60X <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1004.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1004.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 4<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nMoulage, encombrement et superposition nucl\u00e9aires r\u00e9sultant de l&#8217;augmentation marqu\u00e9e de la taille nucl\u00e9aire. Fentes nucl\u00e9aires et inclusions cytoplasmiques intranucl\u00e9aires.<br \/>\n60X <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 4<br \/>\n        \t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nMoulage, encombrement et superposition nucl\u00e9aires r\u00e9sultant de l&#8217;augmentation marqu\u00e9e de la taille nucl\u00e9aire. Fentes nucl\u00e9aires et inclusions cytoplasmiques intranucl\u00e9aires.<br \/>\n60X  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1005.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1005.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 5<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nM\u00eame si les caract\u00e9ristiques observ\u00e9es sur les figures 1 \u00e0 4 suffisent \u00e0 \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire, la pr\u00e9sence de psammomes (comme sur cette image) constitue un plus. Comme ces psammomes sont rarement visibles, leur identification n&#8217;est pas obligatoire pour \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 5<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nM\u00eame si les caract\u00e9ristiques observ\u00e9es sur les figures 1 \u00e0 4 suffisent \u00e0 \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire, la pr\u00e9sence de psammomes (comme sur cette image) constitue un plus. Comme ces psammomes sont rarement visibles, leur identification n&#8217;est pas obligatoire pour \u00e9tablir un diagnostic d\u00e9finitif de carcinome papillaire.<br \/>\n60x\n<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1006.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1006.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 6<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nM\u00eame si elle n&#8217;est pas sp\u00e9cifique au carcinome papillaire, la pr\u00e9sence d&#8217;un collo\u00efde dense (comme sur cette image) est parfois signal\u00e9e dans cette pathologie.<br \/>\n40x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 6<br \/>\n        \t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nM\u00eame si elle n&#8217;est pas sp\u00e9cifique au carcinome papillaire, la pr\u00e9sence d&#8217;un collo\u00efde dense (comme sur cette image) est parfois signal\u00e9e dans cette pathologie.<br \/>\n40x  <\/div>\n<div class=\"newRow\"><\/div>\n<p><strong><em>Suspicion de carcinome papillaire<\/em><\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1007.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1007.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption-small\">\n<strong>Figure 7: <\/strong> Carcinome papillaire.<br \/>\nCet amas de cellules pr\u00e9sente de nombreuses caract\u00e9ristiques (mais pas toutes) d&#8217;un carcinome papillaire (chromatine poudreuse, fentes nucl\u00e9aires, petits nucl\u00e9oles pro\u00e9minents, etc.). A noter l&#8217;absence d&#8217;inclusions cytoplasmiques intranucl\u00e9aires. En outre, les noyaux sont augment\u00e9s en taille, mais pas jusqu&#8217;au moulage ou \u00e0 l&#8217;encombrement. Apr\u00e8s examen histologique de ces \u00e9chantillons, le diagnostic de carcinome papillaire est confirm\u00e9 dans 65 \u00e0 90 % des cas. Pour les 10 \u00e0 35 % restants, le diagnostic de &#8220;suspicion de carcinome papillaire&#8221; convient mieux.<br \/>\n60x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 7<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nCet amas de cellules pr\u00e9sente de nombreuses caract\u00e9ristiques (mais pas toutes) d&#8217;un carcinome papillaire (chromatine poudreuse, fentes nucl\u00e9aires, petits nucl\u00e9oles pro\u00e9minents, etc.). A noter l&#8217;absence d&#8217;inclusions cytoplasmiques intranucl\u00e9aires. En outre, les noyaux sont augment\u00e9s en taille, mais pas jusqu&#8217;au moulage ou \u00e0 l&#8217;encombrement. Apr\u00e8s examen histologique de ces \u00e9chantillons, le diagnostic de carcinome papillaire est confirm\u00e9 dans 65 \u00e0 90 % des cas. Pour les 10 \u00e0 35 % restants, le diagnostic de &#8220;suspicion de carcinome papillaire&#8221; convient mieux.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1008.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1008.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 8<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nComme sur la figure 7, cet amas de cellules pr\u00e9sente presque toutes les caract\u00e9ristiques (mais pas toutes) d&#8217;un carcinome papillaire. Il est difficile de d\u00e9terminer si cet \u00e9chantillon doit \u00eatre class\u00e9 dans la cat\u00e9gorie &#8220;positif&#8221; ou &#8220;suspicion de carcinome papillaire&#8221; (les deux sont corrects). Bien entendu, les cellules visibles sur le reste de l&#8217;\u00e9chantillon peuvent \u00e9galement aider \u00e0 \u00e9tablir un diagnostic d\u00e9finitif.<br \/>\n60X \t<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 8<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\n<br \/>\nComme sur la figure 7, cet amas de cellules pr\u00e9sente presque toutes les caract\u00e9ristiques (mais pas toutes) d&#8217;un carcinome papillaire. Il est difficile de d\u00e9terminer si cet \u00e9chantillon doit \u00eatre class\u00e9 dans la cat\u00e9gorie &#8220;positif&#8221; ou &#8220;suspicion de carcinome papillaire&#8221; (les deux sont corrects). Bien entendu, les cellules visibles sur le reste de l&#8217;\u00e9chantillon peuvent \u00e9galement aider \u00e0 \u00e9tablir un diagnostic d\u00e9finitif.<br \/>\n60X <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>R\u00e9sultat ind\u00e9termin\u00e9 de carcinome papillaire \u2013 Carcinome papillaire avec changement kystique<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1009.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1009.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 9<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nLa transformation kystique caract\u00e9ris\u00e9e par la pr\u00e9sence de macrophages dans le fond est courante dans le carcinome papillaire.<br \/>\n20x    <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 9<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nLa transformation kystique caract\u00e9ris\u00e9e par la pr\u00e9sence de macrophages dans le fond est courante dans le carcinome papillaire.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1010.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1010.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 10<\/strong><br \/>\n<br \/>\nCarcinome papillaire.<br \/>\nQuand un carcinome papillaire devient kystique, ses caract\u00e9ristiques nucl\u00e9aires sont moins apparentes. Ce groupe encombr\u00e9 de cellules fait appara\u00eetre de petits nucl\u00e9oles pro\u00e9minents avec chromatine poudreuse. En revanche, l&#8217;augmentation de la taille nucl\u00e9aire et les membranes irr\u00e9guli\u00e8res ne sont pas \u00e9videntes.<br \/>\n40x  <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n        \t<strong>Figure 10<br \/>\n        \t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nQuand un carcinome papillaire devient kystique, ses caract\u00e9ristiques nucl\u00e9aires sont moins apparentes. Ce groupe encombr\u00e9 de cellules fait appara\u00eetre de petits nucl\u00e9oles pro\u00e9minents avec chromatine poudreuse. En revanche, l&#8217;augmentation de la taille nucl\u00e9aire et les membranes irr\u00e9guli\u00e8res ne sont pas \u00e9videntes.<br \/>\n40x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1011.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1011.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption-small\">\n<strong>Figure 11: <\/strong>Carcinome papillaire.<br \/>\nCe champ provient du m\u00eame \u00e9chantillon que la Figure 10. Les caract\u00e9ristiques nucl\u00e9aires de ce carcinome papillaire confirm\u00e9 par les r\u00e9sultats histologiques sont encore moins apparentes dans ce champ. Comme toutes les l\u00e9sions pr\u00e9sentant quelques caract\u00e9ristiques du carcinome papillaire (avec ou sans changement kystique) ne sont pas des carcinomes papillaires, il est pr\u00e9f\u00e9rable de classer ce type d&#8217;\u00e9chantillons dans la cat\u00e9gorie &#8220;r\u00e9sultat ind\u00e9termin\u00e9 de carcinome papillaire&#8221;. Apr\u00e8s examen histologique de ces \u00e9chantillons, le diagnostic de carcinome papillaire est confirm\u00e9 dans 20 \u00e0 54 % des cas.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 11<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome papillaire.<\/strong><br \/>\nCe champ provient du m\u00eame \u00e9chantillon que la Figure 10. Les caract\u00e9ristiques nucl\u00e9aires de ce carcinome papillaire confirm\u00e9 par les r\u00e9sultats histologiques sont encore moins apparentes dans ce champ. Comme toutes les l\u00e9sions pr\u00e9sentant quelques caract\u00e9ristiques du carcinome papillaire (avec ou sans changement kystique) ne sont pas des carcinomes papillaires, il est pr\u00e9f\u00e9rable de classer ce type d&#8217;\u00e9chantillons dans la cat\u00e9gorie &#8220;r\u00e9sultat ind\u00e9termin\u00e9 de carcinome papillaire&#8221;. Apr\u00e8s examen histologique de ces \u00e9chantillons, le diagnostic de carcinome papillaire est confirm\u00e9 dans 20 \u00e0 54 % des cas.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1012.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1012.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 12<\/strong><br \/>\n<br \/>\nR\u00e9sultat ind\u00e9termin\u00e9 de carcinoma papillaire, ad\u00e9nome trab\u00e9culaire hyalinisant.<br \/>\nGroupe de cellules folliculaires avec irr\u00e9gularit\u00e9s nucl\u00e9aires, petits nucl\u00e9oles pro\u00e9minents et une probable inclusion. Ce pr\u00e9l\u00e8vement effectu\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine a \u00e9t\u00e9 class\u00e9 dans la cat\u00e9gorie &#8220;R\u00e9sultat ind\u00e9termin\u00e9 de carcinome papillaire&#8221;. L&#8217;\u00e9chantillon recueilli \u00e0 la suite de la thyro\u00efdectomie a fait appara\u00eetre un ad\u00e9nome trab\u00e9culaire hyalinisant.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 12<br \/>\n \t\t<\/strong><br \/>\n<strong>R\u00e9sultat ind\u00e9termin\u00e9 de carcinoma papillaire, ad\u00e9nome trab\u00e9culaire hyalinisant.<\/strong><br \/>\nGroupe de cellules folliculaires avec irr\u00e9gularit\u00e9s nucl\u00e9aires, petits nucl\u00e9oles pro\u00e9minents et une probable inclusion. Ce pr\u00e9l\u00e8vement effectu\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine a \u00e9t\u00e9 class\u00e9 dans la cat\u00e9gorie &#8220;R\u00e9sultat ind\u00e9termin\u00e9 de carcinome papillaire&#8221;. L&#8217;\u00e9chantillon recueilli \u00e0 la suite de la thyro\u00efdectomie a fait appara\u00eetre un ad\u00e9nome trab\u00e9culaire hyalinisant.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1013.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1013.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 13<\/strong><br \/>\n<br \/>\nR\u00e9sultat ind\u00e9termin\u00e9 de carcinoma papillaire, ad\u00e9nome trab\u00e9culaire hyalinisant.<br \/>\nOn retrouve ici les fentes nucl\u00e9aires et petits nucl\u00e9oles pro\u00e9minents de la Figure 12. L&#8217;histologie de la l\u00e9sion montre que le mat\u00e9riel amorphe vert entourant ce groupe de cellules est en fait du collag\u00e8ne.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 13<br \/>\n \t\t<\/strong><br \/>\n<strong>R\u00e9sultat ind\u00e9termin\u00e9 de carcinoma papillaire, ad\u00e9nome trab\u00e9culaire hyalinisant.<\/strong><br \/>\nOn retrouve ici les fentes nucl\u00e9aires et petits nucl\u00e9oles pro\u00e9minents de la Figure 12. L&#8217;histologie de la l\u00e9sion montre que le mat\u00e9riel amorphe vert entourant ce groupe de cellules est en fait du collag\u00e8ne.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>Diagnostic positif de carcinome m\u00e9dullaire<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1014.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1014.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 14<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nSur un pr\u00e9l\u00e8vement effectu\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine, un cancer m\u00e9dullaire se pr\u00e9sente g\u00e9n\u00e9ralement sous la forme de groupes l\u00e2ches et de cellules plasmacyto\u00efdes monomorphes isol\u00e9es. Ce champ comporte un fragment d&#8217;amylo\u00efde.<br \/>\n20x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 14<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nSur un pr\u00e9l\u00e8vement effectu\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine, un cancer m\u00e9dullaire se pr\u00e9sente g\u00e9n\u00e9ralement sous la forme de groupes l\u00e2ches et de cellules plasmacyto\u00efdes monomorphes isol\u00e9es. Ce champ comporte un fragment d&#8217;amylo\u00efde.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1015.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1015.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 15<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nUn plus fort grossissement fait appara\u00eetre des cellules rondes, ovales, polygonales ou fusel\u00e9es avec des noyaux d&#8217;aspect similaire. Un fragment d&#8217;amylo\u00efde se trouve dans le coin sup\u00e9rieur droit de l&#8217;image.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 15<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nUn plus fort grossissement fait appara\u00eetre des cellules rondes, ovales, polygonales ou fusel\u00e9es avec des noyaux d&#8217;aspect similaire. Un fragment d&#8217;amylo\u00efde se trouve dans le coin sup\u00e9rieur droit de l&#8217;image.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1016.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1016.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 16<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nUn grossissement encore plus fort permet d&#8217;observer le cytoplasme finement granulaire et la chromatine grossi\u00e8rement granulaire. Les nucl\u00e9oles pro\u00e9minents occasionnels et la binucl\u00e9ation occasionnelle sont caract\u00e9ristiques du cancer m\u00e9dullaire.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 16<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nUn grossissement encore plus fort permet d&#8217;observer le cytoplasme finement granulaire et la chromatine grossi\u00e8rement granulaire. Les nucl\u00e9oles pro\u00e9minents occasionnels et la binucl\u00e9ation occasionnelle sont caract\u00e9ristiques du cancer m\u00e9dullaire.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1017.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1017.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 17<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nDavantage de cellules binucl\u00e9\u00e9es avec amylo\u00efde.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 17<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nDavantage de cellules binucl\u00e9\u00e9es avec amylo\u00efde.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1018.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1018.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 18<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nGroupe l\u00e2che de cellules uniformes principalement petites avec quelques grandes cellules atypiques. Les petites cellules pr\u00e9sentent un noyau excentr\u00e9 et un cytoplasme finement granulaire. Cette figure et les suivantes illustrent une pr\u00e9sentation inhabituelle de cancer m\u00e9dullaire pour une cytoponction \u00e0 l&#8217;aiguille fine.<br \/>\n60x \t<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 18<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nGroupe l\u00e2che de cellules uniformes principalement petites avec quelques grandes cellules atypiques. Les petites cellules pr\u00e9sentent un noyau excentr\u00e9 et un cytoplasme finement granulaire. Cette figure et les suivantes illustrent une pr\u00e9sentation inhabituelle de cancer m\u00e9dullaire pour une cytoponction \u00e0 l&#8217;aiguille fine.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1019.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1019.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 19<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nLe cancer m\u00e9dullaire pr\u00e9sente parfois des nucl\u00e9oles pro\u00e9minents, comme sur cette image. La plupart des cellules ont ici perdu leur cytoplasme.<br \/>\n60x   <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 19<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nLe cancer m\u00e9dullaire pr\u00e9sente parfois des nucl\u00e9oles pro\u00e9minents, comme sur cette image. La plupart des cellules ont ici perdu leur cytoplasme.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1020.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1020.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 20<\/strong><br \/>\n<br \/>\nCarcinome m\u00e9dullaire.<br \/>\nCe champ montre une cellule tumorale tr\u00e8s grande, atypique mais d\u00e9g\u00e9n\u00e9r\u00e9e avec plusieurs petites cellules tumorales uniformes d\u00e9g\u00e9n\u00e9r\u00e9es.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 20<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome m\u00e9dullaire.<\/strong><br \/>\nCe champ montre une cellule tumorale tr\u00e8s grande, atypique mais d\u00e9g\u00e9n\u00e9r\u00e9e avec plusieurs petites cellules tumorales uniformes d\u00e9g\u00e9n\u00e9r\u00e9es.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>Diagnostic positif de carcinome thyro\u00efdien anaplasique<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1021.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1021.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 21<\/strong><br \/>\n<br \/>\nCarcinome anaplasique.<br \/>\nLes deux micro-follicules situ\u00e9s dans la moiti\u00e9 inf\u00e9rieure de l&#8217;image se composent de cellules folliculaires atypiques dont l&#8217;augmentation de taille est variable et certaines contenant des nucl\u00e9oles pro\u00e9minents. Une cellule g\u00e9ante semblable \u00e0 un ost\u00e9oclaste avec grands nucl\u00e9oles pro\u00e9minents se trouve dans la moiti\u00e9 sup\u00e9rieure.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 21<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome anaplasique.<\/strong><br \/>\nLes deux micro-follicules situ\u00e9s dans la moiti\u00e9 inf\u00e9rieure de l&#8217;image se composent de cellules folliculaires atypiques dont l&#8217;augmentation de taille est variable et certaines contenant des nucl\u00e9oles pro\u00e9minents. Une cellule g\u00e9ante semblable \u00e0 un ost\u00e9oclaste avec grands nucl\u00e9oles pro\u00e9minents se trouve dans la moiti\u00e9 sup\u00e9rieure.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1022.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1022.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 22<\/strong><br \/>\n<br \/>\nCarcinome anaplasique.<br \/>\nPlus fort grossissement des micro-follicules de la Figure 21.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 22<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome anaplasique.<\/strong><br \/>\nPlus fort grossissement des micro-follicules de la Figure 21.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1023.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1023.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 23<\/strong><br \/>\n<br \/>\nCarcinome anaplasique.<br \/>\nAutre cellule g\u00e9ante semblable \u00e0 un ost\u00e9oclaste.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 23<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome anaplasique.<\/strong><br \/>\nAutre cellule g\u00e9ante semblable \u00e0 un ost\u00e9oclaste.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1024.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1024.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 24<\/strong><br \/>\n<br \/>\nCarcinome anaplasique.<br \/>\nLa r\u00e9action positive des cellules tumorales \u00e0 la thyroglobuline lors de l&#8217;immunocytochimie confirme leur origine thyro\u00efdienne.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 24<br \/>\n \t\t<\/strong><br \/>\n<strong>Carcinome anaplasique.<\/strong><br \/>\nLa r\u00e9action positive des cellules tumorales \u00e0 la thyroglobuline lors de l&#8217;immunocytochimie confirme leur origine thyro\u00efdienne.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>R\u00e9sultat ind\u00e9termin\u00e9 de tumeur maligne \u2013 N\u00e9oplasme \u00e0 cellules de H\u00fcrthle<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1025.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1025.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 25<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nEn cytologie, les n\u00e9oplasmes \u00e0 cellules de H\u00fcrthle sont caract\u00e9ris\u00e9s par un \u00e9chantillon cellulaire comportant de nombreux groupes manquant de coh\u00e9sion et des cellules de H\u00fcrthle isol\u00e9es.<br \/>\n20x   <\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\">\n \t\t<strong>Figure 25<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nEn cytologie, les n\u00e9oplasmes \u00e0 cellules de H\u00fcrthle sont caract\u00e9ris\u00e9s par un \u00e9chantillon cellulaire comportant de nombreux groupes manquant de coh\u00e9sion et des cellules de H\u00fcrthle isol\u00e9es.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1026.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1026.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 26<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nA fort grossissement, le cytoplasme granulaire mod\u00e9r\u00e9 \u00e0 abondant et les nucl\u00e9oles centraux pro\u00e9minents caract\u00e9risent les cellules de H\u00fcrthle.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 26<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nA fort grossissement, le cytoplasme granulaire mod\u00e9r\u00e9 \u00e0 abondant et les nucl\u00e9oles centraux pro\u00e9minents caract\u00e9risent les cellules de H\u00fcrthle.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1027.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1027.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 27<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nLa binucl\u00e9ation (coin sup\u00e9rieur droit et coin inf\u00e9rieur gauche de ce groupe de cellules) est une autre caract\u00e9ristique des cellules de H\u00fcrthle.<br \/>\n60x   <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 27<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nLa binucl\u00e9ation (coin sup\u00e9rieur droit et coin inf\u00e9rieur gauche de ce groupe de cellules) est une autre caract\u00e9ristique des cellules de H\u00fcrthle.<br \/>\n60x   <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1028.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1028.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 28<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nComme le carcinome m\u00e9dullaire, le n\u00e9oplasme \u00e0 cellules de H\u00fcrthle se pr\u00e9sente sous la forme de nombreux groupes l\u00e2ches et de cellules tumorales isol\u00e9es sur un \u00e9chantillon pr\u00e9lev\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine. En revanche, le cytoplasme est plus abondant dans le n\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\n20x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 28<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nComme le carcinome m\u00e9dullaire, le n\u00e9oplasme \u00e0 cellules de H\u00fcrthle se pr\u00e9sente sous la forme de nombreux groupes l\u00e2ches et de cellules tumorales isol\u00e9es sur un \u00e9chantillon pr\u00e9lev\u00e9 par cytoponction \u00e0 l&#8217;aiguille fine. En revanche, le cytoplasme est plus abondant dans le n\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\n20x   <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1029.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1029.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 29<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nLa binucl\u00e9ation fr\u00e9quente montr\u00e9e sur cette figure repr\u00e9sente une autre caract\u00e9ristique commune au n\u00e9oplasme \u00e0 cellules de H\u00fcrthle et au carcinome m\u00e9dullaire.<br \/>\n60x<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 29<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nLa binucl\u00e9ation fr\u00e9quente montr\u00e9e sur cette figure repr\u00e9sente une autre caract\u00e9ristique commune au n\u00e9oplasme \u00e0 cellules de H\u00fcrthle et au carcinome m\u00e9dullaire.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1030.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1030.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 30<\/strong><br \/>\n<br \/>\nN\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<br \/>\nA fort grossissement, les granules cytoplasmiques et les nucl\u00e9oles des n\u00e9oplasmes \u00e0 cellules de H\u00fcrthle sont plus grands et plus pro\u00e9minents que ceux des carcinomes m\u00e9dullaires.<br \/>\n100x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 30<br \/>\n \t\t<\/strong><br \/>\n<strong>N\u00e9oplasme \u00e0 cellules de H\u00fcrthle.<\/strong><br \/>\nA fort grossissement, les granules cytoplasmiques et les nucl\u00e9oles des n\u00e9oplasmes \u00e0 cellules de H\u00fcrthle sont plus grands et plus pro\u00e9minents que ceux des carcinomes m\u00e9dullaires.<br \/>\n100x <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>R\u00e9sultat ind\u00e9termin\u00e9 de tumeur maligne \u2013 N\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1031.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1031.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 31<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<br \/>\nGroupes encombr\u00e9s de cellules folliculaires sans collo\u00efde dans le fond.<br \/>\n40x<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 31<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<\/strong><br \/>\nGroupes encombr\u00e9s de cellules folliculaires sans collo\u00efde dans le fond.<br \/>\n40x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1032.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1032.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 32<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<br \/>\nA plus fort grossissement, les cellules folliculaires semblent manquer de coh\u00e9sion et pr\u00e9sentent une quantit\u00e9 assez importante de cytoplasme granulaire. En revanche, toutes ces cellules n&#8217;ont pas de grands nucl\u00e9oles pro\u00e9minents.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 32<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<\/strong><br \/>\nA plus fort grossissement, les cellules folliculaires semblent manquer de coh\u00e9sion et pr\u00e9sentent une quantit\u00e9 assez importante de cytoplasme granulaire. En revanche, toutes ces cellules n&#8217;ont pas de grands nucl\u00e9oles pro\u00e9minents.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1033.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1033.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 33<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<br \/>\nLes cellules de H\u00fcrthle situ\u00e9es dans le champ droit de cette image semblent former un microfollicule.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 33<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<\/strong><br \/>\nLes cellules de H\u00fcrthle situ\u00e9es dans le champ droit de cette image semblent former un microfollicule.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1034.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1034.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 34<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<br \/>\nSur cette image montrant une autre partie de l&#8217;\u00e9chantillon que la Figure 33, le manque de coh\u00e9sion de ces cellules de H\u00fcrthle est plus \u00e9vident.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 34<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire avec apparition de cellules de H\u00fcrthle.<\/strong><br \/>\nSur cette image montrant une autre partie de l&#8217;\u00e9chantillon que la Figure 33, le manque de coh\u00e9sion de ces cellules de H\u00fcrthle est plus \u00e9vident.<br \/>\n60x  <\/div>\n<div class=\"newRow\"><\/div>\n<p><em><strong>R\u00e9sultat ind\u00e9termin\u00e9 de tumeur maligne \u2013 N\u00e9oplasme microfolliculaire<\/strong><\/em><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1035.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1035.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 35<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire.<br \/>\nCe grossissement relativement faible fait appara\u00eetre des groupes\/microfollicules encombr\u00e9s dispers\u00e9s avec certains macrophages dans le fond.<br \/>\n20x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 35<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire.<\/strong><br \/>\nCe grossissement relativement faible fait appara\u00eetre des groupes\/microfollicules encombr\u00e9s dispers\u00e9s avec certains macrophages dans le fond.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1036.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1036.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 36<\/strong><br \/>\n<br \/>\nN\u00e9oplasme microfolliculaire.<br \/>\nFort grossissement d&#8217;un microfollicule.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnShortCell\">\n        \t<strong>Figure 36<br \/>\n        \t<\/strong><br \/>\n<strong>N\u00e9oplasme microfolliculaire.<\/strong> <br \/>\nFort grossissement d&#8217;un microfollicule.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<p><strong>L\u00e9sion tr\u00e8s probablement b\u00e9nigne \u2013 concordant avec une l\u00e9sion mixte (micro et macrofolliculaire)<\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1037.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1037.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 37<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nPr\u00e9sence de plusieurs follicules de taille variable.<br \/>\n10x<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 37<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nPr\u00e9sence de plusieurs follicules de taille variable.<br \/>\n10x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1038.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1038.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 38<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nUn plus fort grossissement que la Figure 37 montre des follicules intacts de taille variable.<br \/>\n20x \t<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 38<br \/>\n \t\t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nUn plus fort grossissement que la Figure 37 montre des follicules intacts de taille variable.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1039.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1039.jpg\" alt=\"Image 3\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 39<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nUn grossissement encore plus fort montre un groupe de petits follicules.<br \/>\n40x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n \t\t<strong>Figure 39<br \/>\n \t\t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nUn grossissement encore plus fort montre un groupe de petits follicules.<br \/>\n40x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1040.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1040.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 40<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nCette image montre un macrofollicule et un amas de cellules folliculaires. Qu&#8217;ils se trouvent dans des follicules ou dans des amas, les macrofollicules sont caract\u00e9ris\u00e9s par des cellules folliculaires tr\u00e8s espac\u00e9es.<br \/>\n10x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 40<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nCette image montre un macrofollicule et un amas de cellules folliculaires. Qu&#8217;ils se trouvent dans des follicules ou dans des amas, les macrofollicules sont caract\u00e9ris\u00e9s par des cellules folliculaires tr\u00e8s espac\u00e9es.<br \/>\n10x \t<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1041.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1041.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 41<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nPlus fort grossissement du macrofollicule de la Figure 40.<br \/>\n40x   <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 41<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nPlus fort grossissement du macrofollicule de la Figure 40.<br \/>\n40x \t<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1042.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1042.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 42<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nLe plus souvent, les macrofollicules se pr\u00e9sentent sous la forme d&#8217;amas de cellules folliculaires comme sur cette image.<br \/>\n20x    <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 42<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nLe plus souvent, les macrofollicules se pr\u00e9sentent sous la forme d&#8217;amas de cellules folliculaires comme sur cette image.<br \/>\n20x \t<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1043.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1043.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 43<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nSur les lames ThinPrep, un collo\u00efde appara\u00eet g\u00e9n\u00e9ralement sous la forme d&#8217;un fragment de mat\u00e9riel amorphe homog\u00e8ne avec bord saillant et deux nuances de couleur.<br \/>\n60x   <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 43<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nSur les lames ThinPrep, un collo\u00efde appara\u00eet g\u00e9n\u00e9ralement sous la forme d&#8217;un fragment de mat\u00e9riel amorphe homog\u00e8ne avec bord saillant et deux nuances de couleur.<br \/>\n60x \t<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1044.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1044.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 44<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nLe collo\u00efde peut \u00e9galement pr\u00e9senter une texture l\u00e9g\u00e8rement irr\u00e9guli\u00e8re sur une lame ThinPrep.<br \/>\n60x  <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 44<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nLe collo\u00efde peut \u00e9galement pr\u00e9senter une texture l\u00e9g\u00e8rement irr\u00e9guli\u00e8re sur une lame ThinPrep.<br \/>\n60x\t<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1045.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1045.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 45<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nLe fragment de collo\u00efde au centre d&#8217;un follicule montre des artefacts de fissuration.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 45<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nLe fragment de collo\u00efde au centre d&#8217;un follicule montre des artefacts de fissuration.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1046.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1046.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 46<\/strong><br \/>\n<br \/>\nL\u00e9sion macrofolliculaire.<br \/>\nCe mat\u00e9riel \u00e0 l&#8217;aspect de papier s&#8217;est av\u00e9r\u00e9 fortement associ\u00e9 \u00e0 la quantit\u00e9 de collo\u00efde sur l&#8217;\u00e9chantillon recueilli apr\u00e8s thyro\u00efdectomie et repr\u00e9sente tr\u00e8s probablement un collo\u00efde s\u00e9reux.<br \/>\n40x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 46<br \/>\n        \t<\/strong><br \/>\n<strong>L\u00e9sion macrofolliculaire.<\/strong><br \/>\nCe mat\u00e9riel \u00e0 l&#8217;aspect de papier s&#8217;est av\u00e9r\u00e9 fortement associ\u00e9 \u00e0 la quantit\u00e9 de collo\u00efde sur l&#8217;\u00e9chantillon recueilli apr\u00e8s thyro\u00efdectomie et repr\u00e9sente tr\u00e8s probablement un collo\u00efde s\u00e9reux.<br \/>\n40x <\/div>\n<div class=\"newRow\"><\/div>\n<p><strong><em>Absence de cellules malignes concordant avec une thyro\u00efdite de Hashimoto<\/em><\/strong><\/p>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1047.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1047.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 47<\/strong><br \/>\n<br \/>\nThyro\u00efdite de Hashimoto.<br \/>\nPr\u00e9sence de nombreuses cellules mononucl\u00e9aires avec cytoplasme rare et d&#8217;un follicule lympho\u00efde.<br \/>\n20x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 47<br \/>\n        \t<\/strong><br \/>\n<strong>Thyro\u00efdite de Hashimoto.<\/strong><br \/>\nPr\u00e9sence de nombreuses cellules mononucl\u00e9aires avec cytoplasme rare et d&#8217;un follicule lympho\u00efde.<br \/>\n20x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1048.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1048.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 48<\/strong><br \/>\n<br \/>\nThyro\u00efdite de Hashimoto.<br \/>\nUn plus fort grossissement montre les cellules mononucl\u00e9aires et le follicule lympho\u00efde avec cellules lympho\u00efdes \u00e0 divers stades de maturation.<br \/>\n40x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 48<br \/>\n        \t<\/strong><br \/>\n<strong>Thyro\u00efdite de Hashimoto.<\/strong><br \/>\nUn plus fort grossissement montre les cellules mononucl\u00e9aires et le follicule lympho\u00efde avec cellules lympho\u00efdes \u00e0 divers stades de maturation.<br \/>\n40x  <\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\">\n<a href=\"\/gallery\/images_large\/slide1049.jpg\" class=\"highslide\" onclick=\"return hs.expand(this)\"><br \/>\n\t<img decoding=\"async\" src=\"\/gallery\/images\/slide1049.jpg\" alt=\"Image 2\" title=\"Click to enlarge\" border=\"0\"><\/a><\/p>\n<div class=\"highslide-caption\">\n<strong>Figure 49<\/strong><br \/>\n<br \/>\nThyro\u00efdite de Hashimoto.<br \/>\nGroupe coh\u00e9sif de cellules de H\u00fcrthle avec cytoplasme granulaire.<br \/>\n60x <\/div>\n<\/div>\n<div class=\"chartColumnLongCell\">\n        \t<strong>Figure 49<br \/>\n        \t<\/strong><br \/>\n<strong>Thyro\u00efdite de Hashimoto.<\/strong><br \/>\nGroupe coh\u00e9sif de cellules de H\u00fcrthle avec cytoplasme granulaire.<br \/>\n60x <\/div>\n<div class=\"newRow\"><\/div>\n<p><a class=\"back\" href=\"#\">Retour au d\u00e9but<\/a><\/p>\n<p><a href=\"nongyn_atlas.htm\">Retour \u00e0 la table des mati\u00e8res<\/a><\/p>\n<\/div><\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_widget_sidebar sidebar_id=&#8221;consulting-right-sidebar&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]PGNlbnRlcj48YSBjbGFzcz0ic2hpZnRuYXYtdG9nZ2xlIHNoaWZ0bmF2LXRvZ2dsZS1idXR0b24iIGRhdGEtc2hpZnRuYXYtdGFyZ2V0PSJzaGlmdG5hdi1tYWluIj48aSBjbGFzcz0iZmEgZmEtYmFycyI+PC9pPiBUYWJsZSBvZiBDb250ZW50cyA8L2E+PC9jZW50ZXI+[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;Cytoponction \u00e0 l&#8217;aiguille fine&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text] Thyro\u00efde Helen H. Wang, MD, DrPH Introduction Les nodules thyro\u00efdiens font partie des d\u00e9couvertes cliniques courantes, avec un taux annuel d&#8217;incidence estim\u00e9 \u00e0 4-8 %. [1] On estime qu&#8217;entre 10 et 20 millions d&#8217;Am\u00e9ricains souffrent de nodules thyro\u00efdiens cliniquement d\u00e9tectables. [1] Comme<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":1949,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2056","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/pages\/2056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/comments?post=2056"}],"version-history":[{"count":0,"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/pages\/2056\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/pages\/1949"}],"wp:attachment":[{"href":"https:\/\/stage.cytologystuff.com\/fr\/wp-json\/wp\/v2\/media?parent=2056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}