{"id":2016,"date":"2017-08-01T13:28:04","date_gmt":"2017-08-01T13:28:04","guid":{"rendered":"http:\/\/cytologystuff1.wpengine.com\/1587-2\/non-gyn-atlas\/fine-needle-aspiration-cytology-breast\/"},"modified":"2018-01-12T05:44:21","modified_gmt":"2018-01-12T05:44:21","slug":"fine-needle-aspiration-cytology-breast","status":"publish","type":"page","link":"https:\/\/stage.cytologystuff.com\/it\/1587-2\/non-gyn-atlas\/fine-needle-aspiration-cytology-breast\/","title":{"rendered":"itologia degli aspirati con ago sottile &#8211; MAMMELLA"},"content":{"rendered":"<p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]JTNDY2VudGVyJTNFJTNDYSUyMGNsYXNzJTNEJTIyc2hpZnRuYXYtdG9nZ2xlJTIwc2hpZnRuYXYtdG9nZ2xlLWJ1dHRvbiUyMiUyMGRhdGEtc2hpZnRuYXYtdGFyZ2V0JTNEJTIyc2hpZnRuYXYtbWFpbiUyMiUzRSUzQ2klMjBjbGFzcyUzRCUyMmZhJTIwZmEtYmFycyUyMiUzRSUzQyUyRmklM0UlMjBUYWJsZSUyMG9mJTIwQ29udGVudHMlMjAlM0MlMkZhJTNFJTNDJTJGY2VudGVyJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;itologia degli aspirati con ago sottile &#8211; MAMMELLA&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<div>\n<p class=\"subhead\">MAMMELLA<br \/>\n<em>Grace T. McKee, medico <\/em><\/p>\n<p><strong> Introduzione<\/strong><\/p>\n<p>La mammella \u00e8 costituita da adipe e stroma che supportano il tessuto ghiandolare, un sistema duttale con diramazioni collegate a 6-10 dotti principali che sboccano nel capezzolo. Nella mammella possono svilupparsi lesioni benigne e maligne. In giovane et\u00e0, sono molto diffusi i fibroadenomi, ma con il passare degli anni diventano pi\u00f9 comuni le lesioni fibrocistiche. Altre lesioni benigne sono ad esempio necrosi adipose e condizioni infiammatorie come ascessi e mastiti. Pi\u00f9 raramente, possono presentarsi alter lesioni benigne come gli amartomi e le iperplasie pseudoangiomatose. L&#8217;iperplasia duttale rientra nella categoria delle lesioni fibrocistiche. Pu\u00f2 essere molto difficile distinguere l&#8217;iperplasia duttale atipica dal carcinoma duttale di basso grado in situ e entrambe possono evolvere in un carcinoma mammario. Le alterazioni da radiazioni possono dare origine a una massa che pu\u00f2 apparire atipica all\u2019aspirazione . Analogamente, le alterazioni dovute alla gravidanza e alla lattazione possono essere confuse negli agoaspirati con alterazioni maligne ed \u00e8 quindi essenziale valutare accuratamente le informazioni cliniche per giungere a una diagnosi citologica corretta.<\/p>\n<p>Le patologie maligne della mammella possono essere primitive o metastatiche. Queste ultime comprendono linfomi, melanomi maligni e altri tumori secondari come carcinomi renali, bronchiali, ovarici o polmonari. Il pi\u00f9 significativo da un punto di vista diagnostico \u00e8 il carcinoma duttale primitivo della mammella , non altrimenti specificato (NAS). La seconda neoplasia mammaria primitiva pi\u00f9 diffusa \u00e8 il carcinoma lobulare. Il carcinoma duttale in situ e il carcinoma lobulare in situ vengono diagnosticati con facilit\u00e0 nelle biopsie escissionali, ma presentano maggiori difficolt\u00e0 di individuazione all\u2019 esame citologico.<\/p>\n<p>La citologia mammaria \u00e8 un utile strumento sia a fini di screening che diagnostici. Su qualsiasi lesione rilevata grazie allo screening mammografico pu\u00f2 essere eseguita una biopsia con ago sottile, mediante aspirazione diretta se la lesione \u00e8 palpabile o mediante stereotassi o guida ecografia , se non palpabile. Se il campione citologico \u00e8 inadeguato o dubbio , ci si pu\u00f2 avvalere della biopsia percutanea o della sezione congelata. Le masse palpabili della mammella possono essere agevolmente aspirate e processate per una diagnosi tempestiva.<\/p>\n<p>La citologia agoaspirativa rappresenta dunque un utile strumento per la diagnosi delle lesioni mammarie, siano esse palpabili o meno. Si tratta di una procedura sicura, rapida, poco costosa (se confrontata con le biopsie percutanee) e relativamente indolore e pu\u00f2 essere eseguita sia dai medici che dai patologi. Se l&#8217;esame \u00e8 eseguito dai citopatologi, il tasso di inadeguatezza \u00e8 pi\u00f9 basso perch\u00e9 questi con colorazioni rapide possono valutare l&#8217;adeguatezza dei campioni e quindi ripetere il prelievo, se necessario. La correlazione cito-istologica \u00e8 un carta vincente nelle mani dei citopatologi esperti. Uno svantaggio degli aspirati con ago sottile \u00e8 rappresentato dal fatto che non sempre \u00e8 possibile distinguere tra lesioni invasive e in situ, ma in alcuni casi anche le biopsie percutanee presentano questo tipo di problema.<\/p>\n<p>Il materiale aspirato viene strisciato su un vetrino o immesso in una soluzione Cytolyt<sup>\u00ae<\/sup> e l&#8217;ago viene risciacquato con la stessa soluzione. Il fluido pu\u00f2 essere utilizzato per ottenere vari vetrini praticamente identici e consentire quindi ai laboratoridi conservare materiale per le colorazioni speciali, ad esempio recettori per estrogeno e progesterone e sovraespressione della proteina HER2\/neu.<\/p>\n<p><strong>CARATTERISTICHE CITOLOGICHE <\/strong><br \/>\n<strong> Caratteristiche benigne <\/strong><br \/>\nGli aspirati di un mammella normale contengono solo adipe, stroma e alcune cellule duttali benigne. \u00c8 raro che si esegua un aspirato di una mammella normale, a meno che l&#8217;ago non manchi la reale lesione. Gli aspirati di una mammella normale non soddisfano infatti il criterio di adeguatezza largamente riconosciuto per questo tipo di aspirati: la presenza di almeno cinque o sei aggregati di cellule epiteliali. Eccezioni alla regola sono necrosi adipose e lesioni infiammatorie.<\/p>\n<p>Gli aspirati di mastiti e ascessi mammari contengono numerosi neutrofili, istiociti, istiociti giganti polinucleati, qualche cellula epiteliale deteriorata e materiale proteinaceo che pu\u00f2 simulare una necrosi. Si tratta di elementi abbastanza frequenti nelle donne che allattano. Le <strong>necrosi adipose<\/strong> si sviluppano in seguito a un trauma (un colpo diretto al seno, un intervento chirurgico o la radioterapia). Da un punto di vista clinico e mammografico, le necrosi adipose possono far sospettare un carcinoma perch\u00e9 si presentano come una massa dura e irregolare. Tuttavia, l&#8217;analisi dell&#8217;aspirato consente di rilevare la presenza di adipociti deteriorati con numerosi macrofagi che consentono di formulare una diagnosi corretta.<\/p>\n<p>Il fibroadenoma della mammella si presenta come una massa compatta, regolare e mobile. Ha spesso una consistenza gommosa e trattiene la punta dell&#8217;ago. Gli aspirati sono in genere ad elevata cellularit\u00e0 e presentano grandi lembi di cellule duttali benigne, con varie diramazioni, e sporadiche cellule mioepiteliali (simili a &#8220;semi di sesamo &#8221; sulla superficie). Negli strisci ThinPrep, le singole cellule mioepiteliali del fondo tendono ad accumularsi accanto alle cellule duttali. Le cellule duttali mostrano spesso sovrapposizione,il che suggerisce una iperplasia duttale. Sono visibili frammenti stromali di varie dimensioni che contengono nuclei fusiformi.<\/p>\n<p>Anche i tumori filloidi di basso grado hanno una composizione fibroepiteliale, con elementi ghiandolari che assomigliano marcatamente a quelli del fibroadenoma. Tuttavia, nei tumori filloidi l&#8217;iperplasia duttale \u00e8 molto pi\u00f9 comune. La componente stromale tende a essere importante, con grandi frammenti ipercellulari. I tumori filloidi maligni mostrano inequivocabilmente le caratteristiche proprie dei tumori maligni.<\/p>\n<p>Le lesioni fibrocistiche rappresentano una categoria piuttosto diffusa che comprende lesioni cistiche con metaplasia apocrina, iperplasia duttale comune e altre forme di epiteliosi. L&#8217;esame citologico evidenzia lembi e gruppi di cellule duttali benigne sovrapposte con cellule mioepiteliali, metaplasia apocrina, macrofagi spugnosi e calcio. Queste caratteristiche possono ricordare quelle citologiche di un fibroadenoma, tuttavia il quadro clinico evidenzia un ispessimento o un rilievo non ben definiti piuttosto che la massa mobile e regolare tipica del fibroadenoma. Le alterazioni cistiche possono subire evoluzioni fino a divenire cisti palpabili che possono essere aspirate con facilit\u00e0. Il fluido estratto pu\u00f2 apparire chiaro e incolore oppure torbido, marrone, verde o ematico. I fluidi provenienti dalle cisti contengono materiale proteico, cellule duttali benigne che possono apparire deteriorate o lievemente atipiche, cellule apocrine metaplastiche e macrofagi schiumosi. Un fluido di colore marrone o verde indica di solito un sanguinamento di vecchia data, che pu\u00f2 essere confermato dalla presenza sul vetrino di macrofagi carichi di emosiderina. Le cellule apocrine metaplastiche presentano un abbondante citoplasma granulare, nuclei tondi e nucleoli prominenti. Possono essere binucleate ed apparire atipiche a causa della dimensione nucleare variabile.<\/p>\n<p>La sferulosi collagena \u00e8 una lesione benigna che pu\u00f2 essere associata all&#8217;iperplasia duttale o lobulare. Gli aspirati mostrano globuli di materiale extracellulare (che si colorano di azzurro con colorante Papanicolaou e con Diff-Quick), metaplasia apocrina duttale benigna e cellule mioepiteliali. La diagnosi differenziale comprende carcinoma adenoideo cistico.<\/p>\n<p><strong>Caratteristiche maligne<\/strong><br \/>\nLe caratteristiche che suggeriscono la presenza di malignit\u00e0 includono perdita di coesione cellulare, aumento delle dimensioni cellulari e\/o nucleari, irregolarit\u00e0 delle membrane nucleari, aggregazioni e distribuzione non uniforme della cromatina e nucleoli atipici. Singoli nucleoli sono visibili in condizioni reattive e non costituiscono di per s\u00e8 un criterio sufficiente di malignit\u00e0. Le cellule mioepiteliali, abbondanti nelle lesioni proliferative benigne, non sono visibili negli aspirati del carcinoma invasivo del seno.<\/p>\n<p>Il carcinoma duttale \u00e8 in genere monolaterale. Dal punto di vista clinico, si presenta come una massa irregolare da compatta a dura, con il tipico aspetto mammografico di una massa, di una lesione a margini irregolari o di microcalcificazioni. Sebbene si ritenga che il carcinoma duttale in situ anticipi il carcinoma duttale invasivo, per\u00f2 questo pu\u00f2 anche essere associato a un carcinoma lobulare invasivo. Analogamente, il carcinoma lobulare in situ pu\u00f2 essere associato al carcinoma duttale o al carcinoma lobulare invasivo. Gli agoaspirati del carcinoma duttale in situ mostrano aspetti di malignit\u00e0, ma possono contenere anche cellule mioepiteliali sovrapposte agli aggregati di cellule. Gli aspirati del carcinoma duttale invasivo (NAS) mostrano cellule tumorali grandi e spesso pleomorfe. Pu\u00f2 essere molto difficile distinguere i carcinomi duttali di basso grado dalle cellule duttali benigne. La presenza di un tumore invasivo \u00e8 suggerita dalle cellule tumorali infiltratesi tra gli adipociti.<\/p>\n<p>Il carcinoma lobulare \u00e8 spesso bilaterale. Dal punto di vista clinico, il tumore non \u00e8 ben definito e non ha un aspetto mammografico caratteristico. Il carcinoma lobulare in situ \u00e8 caratterizzato da aggregati tondeggianti di piccole cellule maligne, alcune delle quali presentano vacuoli intracitoplasmatici, spesso con sovrapposizione di cellule mioepiteliali. Gli agoaspirati del carcinoma lobulare invasivo sono scarsamente cellulati e spesso i referti risultano &#8220;inadeguati&#8221; o &#8220;atipici&#8221;. Le cellule sono pi\u00f9 piccole rispetto a quelle del carcinoma duttale e si presentano spesso singolarmente con nuclei eccentrici e vacuoli intracitoplasmatici. Solitamente i nucleoli non sono visibili. Le cellule sono sovente disposte in un&#8217;unica fila. Negli agoaspirati del carcinoma lobulare \u00e8 possibile rilevare cellule ad &#8220;anello con castone&#8221;.<\/p>\n<p>Vi sono inoltre particolari tipi di carcinoma duttale come ad esempio carcinomi tubulari, colloidi (mucinosi), metaplastici, midollari, apocrini e squamosi. La definizione di molti di questi particolari tipi di tumore mammari si fonda sul fatto che pi\u00f9 del 90% della lesione presenta le caratteristiche tipiche del tipo di tumore in questione. Poich\u00e9 con l&#8217;esame citologico si campiona solo una parte del tumore, non \u00e8 corretto classificare questi tumori come tubulari o mucinosi. Nel referto \u00e8 possibile sottolineare l&#8217;incertezza includendo una descrizione come &#8220;carcinoma duttale con caratteristiche mucinose o tubulari&#8221; piuttosto che con un tipo di tumore definito, che potrebbe non corrispondere a quello riscontrato nel campione escissionale. I carcinomi tubulari sono costituiti da strutture tubulari e acinari. Gli aspirati del carcinoma mucinoso sono spesso vistosamente mucoidi e nello striscio \u00e8 presente abbondante mucina. Possono svilupparsi anche alcune patologie piuttosto rare, come il carcinoma adenoideo cistico, identico a quello che si osserva nella ghiandola salivare. Questo tumore ricorda la sferulosi collagena benigna perch\u00e9 contiene materiale ialino extracellulare con le stesse caratteristiche tintoriali, ma in forma di globuli o strutture tubulari o cilindriche. Le cellule tumorali associate sono piccole e regolari con citoplasma quasi assente, ma non si osservano cellule duttali, apocrine e metaplastiche benigne.<\/p>\n<p><strong> Bibliografia di riferimento<\/strong><\/p>\n<ol class=\"normal\">\n<li>Aquel NM, Howard S, Collier DS. Fat necrosis of the breast: a cytological and clinical study. Breast 2001;10:342-5.<\/li>\n<li>Jain S, Kumar NK, Sodhani P, et al. Cytology of collagenous spherulosis of the breast: a diagnostic dilemma \u00e2\u20ac\u201c report of three cases. Cytopathology 2002;13:116-20.<\/li>\n<li>Kanhoush R, Jorda M, Gomez-Fernandez C, et al. &#8216;Atypical&#8217; and &#8216;suspicious&#8217; diagnoses in breast aspiration cytology. Cancer 2004;102:164-7.<\/li>\n<li>Bonzanini M, Gilioli E, Brancato B, et al. The cytopathology of ductal carcinoma in situ of the breast. A detailed analysis of fine needle aspiration cytology of 58 cases compared with 101 invasive ductal carcinomas. Cytopathology 2001;12:107-19.<\/li>\n<li>McKee GT, Tambouret RH, Finkelstein D. Fine-needle aspiration cytology of the breast: Invasive vs in situ carcinoma. Diagn Cytopathol 2001;25:73-7.<\/li>\n<li>Klijanienko J, Katsahian S, Vielh P, et al. Stromal infiltration as a predictor of tumor invasion in breast fine-needle aspiration biopsy. Diagn Cytopathol 2004;30:182-6.<\/li>\n<li>Chhieng DC, Fernandez G, Cangiarella JF, et al. Invasive carcinoma in clinically suspicious breast masses diagnosed as adenocarcinoma by fine-needle aspiration. Cancer 2000;90:96-101.<\/li>\n<li>Greeley CF, Frost AR. Cytologic features of ductal and lobular carcinoma in fine needle aspirates of the breast. Acta Cytol 1997;41:333-40.<\/li>\n<li>Ustun M, Berner A, Davidson B, et al. Fine-needle aspiration cytology of lobular carcinoma in situ. Diagn Cytopathol 2002;27:22-6.<\/li>\n<li>Hwang S, Loffe O, Lee I, et al. Cytologic diagnosis of invasive lobular carcinoma: factors associated with negative and equivocal diagnoses. Diagn Cytopathol 2004;31:87-93.<\/li>\n<li>Abdulla M, Hombal S, Al-Juwaiser A, et al. Cellularity of lobular carcinoma and its relationship to false negative fine needle aspiration results. Acta Cytol 2000;44:625-32.<\/li>\n<li>Rajesh L, Dey P, Joshi K. Fine needle aspiration cytology of lobular breast carcinoma. Comparison with other breast lesions. Acta Cytol 2003;47:177-82.<\/li>\n<li>Cangiarella J, Waisman J, Shapiro RL, et al. Cytologic features of tubular adenocarcinoma of the breast by aspiration biopsy. Diagn Cytopathol 2001;25:311-5.<\/li>\n<li>Ventura K, Cangiarella J, Lee I, et al. Aspiration biopsy of mammary lesions with abundant extracellular mucinous material. Review of 43 cases with surgical follow-up. Am J Clin Pathol 2003;120:194-202.<\/li>\n<li>Gupta RK, Naran S, Lallu S, et al. Needle aspiration cytodiagnosis of mucinous (colloid) carcinoma of male breast. Pathology 2003;35:539-40.<\/li>\n<li>Michael CW, Buschmann B. Can true papillary neoplasms of breast and their mimickers be accurately classified by cytology: Cancer 2002;96:92-100.<\/li>\n<li>Simsir A, Waisman J, Thorner K, et al. Mammary lesions diagnosed as papillary&#8217; by aspiration biopsy. 70 cases with follow-up. Cancer 2003;99:156-65.<\/li>\n<li>Levine PH, Zamuco R, Yee HT. Role of fine-needle aspiration cytology in breast lymphoma. Diagn Cytopathol 2004;30:332-40.<\/li>\n<li>Saqi A, Mercado CI, Hamele-Bena D. Adenoid cystic carcinoma of the breast diagnosed by fine needle aspiration. Diagn Cytopathol 2004;30:271-4.<\/li>\n<li>Lee WY. Cytology of abnormal nipple discharge: a cyto-histological correlation. Cytopathology 2003;14:19-26.<\/li>\n<li>Pritt B, Pang Y, Kellogg M, et al. Diagnostic value of nipple cytology: study of 466 cases. Cancer 2004;102:233-8.<\/li>\n<li>Gupta RK, Simpson J, Dowle C. The role of cytology in the diagnosis of Paget&#8217;s disease of the nipple. Pathology 1996;28:248-50.<\/li>\n<\/ol>\n<p style=\"padding-left: 7px;\"><a style=\"width: 350px; display: block;\"><img loading=\"lazy\" decoding=\"async\" id=\"selfAssessImg\" src=\"\/images\/button27h.gif\" width=\"350\" height=\"40\" \/><\/a><\/p>\n<div class=\"highslide-gallery\"><strong>Ricorda: Puoi cliccare su qualsiasi immagine per ingrandire l&#8217;immagine.<\/strong><\/p>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1101.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1101.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 1<\/strong><\/p>\n<p>Agoaspirato mammario, grasso.<br \/>\nLe cellule adipose, o adipociti, sono grandi cellule di forma sferica con citoplasma traslucido e piccoli nuclei eccentrici. Possono essere presenti sia negli agoaspirati benigni che in quelli maligni.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 1<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, grasso.<\/strong><br \/>\nLe cellule adipose, o adipociti, sono grandi cellule di forma sferica con citoplasma traslucido e piccoli nuclei eccentrici. Possono essere presenti sia negli agoaspirati benigni che in quelli maligni.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1102.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1102.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 2<\/strong><\/p>\n<p>Agoaspirato mammario, cellule duttali benigne.<br \/>\nGli agoaspirati di tessoto mammario normale contengono cellule duttali benigne, spesso associate a cellule mioepiteliali.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 2<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cellule duttali benigne.<\/strong><br \/>\nGli agoaspirati di tessoto mammario normale contengono cellule duttali benigne, spesso associate a cellule mioepiteliali.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1103.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1103.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 3<br \/>\n<\/strong><br \/>\nAgoaspirato mammario, ascesso.<br \/>\nGli agoaspirati di ascessi mammari non contengono in genere cellule epiteliali. Sono invece spesso presenti detriti cellulari, globuli rossi lisati e neutrofili.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 3<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, ascesso.<\/strong><br \/>\nGli agoaspirati di ascessi mammari non contengono in genere cellule epiteliali. Sono invece spesso presenti detriti cellulari, globuli rossi lisati e neutrofili.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1104.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1104.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 4: <\/strong> Agoaspirato mammario, fibroadenoma.<br \/>\n\u00c8 presente un grosso frammento stromale con nuclei piccoli e fusiformi. I frammenti stromali sono rilevabili negli aspirati di tessuti mammari benigni e nelle lesioni fibroepiteliali come il fibroadenoma. I frammenti stromali riferibili a tumori filloidi contengono un numero molto pi\u00f9 elevato di cellule. \u00c8 possibile notare anche un piccolo gruppo di cellule duttali benigne.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 4<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\n\u00c8 presente un grosso frammento stromale con nuclei piccoli e fusiformi. I frammenti stromali sono rilevabili negli aspirati di tessuti mammari benigni e nelle lesioni fibroepiteliali come il fibroadenoma. I frammenti stromali riferibili a tumori filloidi contengono un numero molto pi\u00f9 elevato di cellule. \u00c8 possibile notare anche un piccolo gruppo di cellule duttali benigne.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1105.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1105.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 5<\/strong><\/p>\n<p>Agoaspirato mammario, fibroadenoma.<br \/>\nUn grande lembo di cellule duttali benigne coese e uniformi sovrapposto a un lembo di cellule stremali. All&#8217;interno del frammento di cellule stromale \u00e8 possibile notare i nuclei piccoli e fusiformi.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 5<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nUn grande lembo di cellule duttali benigne coese e uniformi sovrapposto a un lembo di cellule stremali. All&#8217;interno del frammento di cellule stromale \u00e8 possibile notare i nuclei piccoli e fusiformi.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1106.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1106.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 6<\/strong><\/p>\n<p>Agoaspirato mammario, fibroadenoma.<br \/>\nIn genere, gli aspirati di un fibroadenoma contengono grandi lembi di cellule duttali benigne, con varie ramificazioni, come mostrato in figura.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 6<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nIn genere, gli aspirati di un fibroadenoma contengono grandi lembi di cellule duttali benigne, con varie ramificazioni, come mostrato in figura.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1107.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1107.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 7<\/strong><\/p>\n<p>Agoaspirato mammario, fibroadenoma.<br \/>\nUn altro esempio di cellule duttali con ramificazioni riconducibili a un fibroadenoma.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 7<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nUn altro esempio di cellule duttali con ramificazioni riconducibili a un fibroadenoma.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1108.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1108.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 8<\/strong><\/p>\n<p>Agoaspirato mammario, fibroadenoma.<br \/>\nIn alcuni casi i gruppi di cellule duttali presentano piccole sporgenze arrotondate come quelle illustrate in figura invece delle lunghe diramazioni come nelle due foto precedenti.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 8<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nIn alcuni casi i gruppi di cellule duttali presentano piccole sporgenze arrotondate come quelle illustrate in figura invece delle lunghe diramazioni come nelle due foto precedenti.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1109.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1109.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 9:<\/strong> Agoaspirato mammario, fibroadenoma.<br \/>\nIn questo campo i bordi del gruppo di cellule duttali non sono regolari come nelle due precedenti immagini, probabilmente a causa dell&#8217; allestimento in fase liquida. All&#8217;interno del gruppo di cellule duttali e sul bordo superiore, sono presenti alcune cellule mioepiteliali. Con il sistema ThinPrep, le cellule mioepiteliali tendono a posizionarsi accanto ai gruppi duttali piuttosto che a disperdersi nello sfondo come si osserva negli strisci convenzionali.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 9<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nIn questo campo i bordi del gruppo di cellule duttali non sono regolari come nelle due precedenti immagini, probabilmente a causa dell&#8217; allestimento in fase liquida. All&#8217;interno del gruppo di cellule duttali e sul bordo superiore, sono presenti alcune cellule mioepiteliali. Con il sistema ThinPrep, le cellule mioepiteliali tendono a posizionarsi accanto ai gruppi duttali piuttosto che a disperdersi nello sfondo come si osserva negli strisci convenzionali.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1110.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1110.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 10<\/strong><\/p>\n<p>Agoaspirato mammario, fibroadenoma.<br \/>\nCellule mioepiteliali sopra un lembo ramificato di cellule duttali benigne che assumono il caratteristico aspetto di &#8220;semi di sesamo sopra al pane&#8221;.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 10<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, fibroadenoma.<\/strong><br \/>\nCellule mioepiteliali sopra un lembo ramificato di cellule duttali benigne che assumono il caratteristico aspetto di &#8220;semi di sesamo sopra al pane&#8221;.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1111.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1111.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption-small\"><strong>Figura 11: <\/strong> Agoaspirato mammario, tumore filloide di basso grado.<br \/>\nI tumori filloidi sono, come i fibroadenomi, anche lesioni fibroepiteliali. Anche le lesioni di basso grado potrebbero ripresentarsi qualora non venissero escisse con ampi margini. La componente ghiandolare \u00e8 simile a quella osservata nel fibroadenoma, anche se appare maggiormente iperplastica e costituita da molte pi\u00f9 cellule . Questa immagine mostra un gruppo tridimensionale di cellule duttali caratterizzate da sovrapposizione e affollamento nucleare, suggestive di iperplasia.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 11<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, tumore filloide di basso grado.<\/strong><br \/>\nI tumori filloidi sono, come i fibroadenomi, anche lesioni fibroepiteliali. Anche le lesioni di basso grado potrebbero ripresentarsi qualora non venissero escisse con ampi margini. La componente ghiandolare \u00e8 simile a quella osservata nel fibroadenoma, anche se appare maggiormente iperplastica e costituita da molte pi\u00f9 cellule . Questa immagine mostra un gruppo tridimensionale di cellule duttali caratterizzate da sovrapposizione e affollamento nucleare, suggestive di iperplasia.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1112.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1112.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 12<\/strong><\/p>\n<p>Agoaspirato mammario, tumore filloide di basso grado.<br \/>\nQuesto \u00e8 un frammento stromale ipercellulare contiene cellule fusiformi assembrate e ingrossate. Sul fondo sono visibili anche numerose cellule stromali fusiformi singole.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 12<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, tumore filloide di basso grado.<\/strong><br \/>\nQuesto \u00e8 un frammento stromale ipercellulare contiene cellule fusiformi assembrate e ingrossate. Sul fondo sono visibili anche numerose cellule stromali fusiformi singole.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1113.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1113.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 13<\/strong><\/p>\n<p>Agoaspirato mammario, alterazioni fibrocistiche.<br \/>\nIn questo campo si osserva un aggregato compatto di cellule duttali benigne con macrofagi schiumosi alle estremit\u00e0 e materiale secretivo di fondo.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 13<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, alterazioni fibrocistiche.<\/strong><br \/>\nIn questo campo si osserva un aggregato compatto di cellule duttali benigne con macrofagi schiumosi alle estremit\u00e0 e materiale secretivo di fondo.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1114.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1114.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 14<\/strong><\/p>\n<p>Agoaspirato mammario, alterazioni fibrocistiche.<br \/>\nQuesto piccolo gruppo di cellule duttali benigne proviene da un agoaspirato di una lesione fibrocistiche.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 14<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, alterazioni fibrocistiche.<\/strong><br \/>\nQuesto piccolo gruppo di cellule duttali benigne proviene da un agoaspirato di una lesione fibrocistiche.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1115.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1115.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 15<\/strong><\/p>\n<p>Agoaspirato mammario, alterazioni fibrocistiche.<br \/>\nNelle lesioni fibrocistiche sono presenti sullo sfondo materiale secretivo, emazie e cellule apocrine metaplastiche.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 15<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, alterazioni fibrocistiche.<\/strong><br \/>\nNelle lesioni fibrocistiche sono presenti sullo sfondo materiale secretivo, emazie e cellule apocrine metaplastiche.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1116.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1116.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 16<\/strong><\/p>\n<p>Agoaspirato mammario, cisti mammaria.<br \/>\nQuesto aggregato di cellule duttali benigne mostra lievi atipie con nucleoli visibili e lieve ingrandimento nucleare. Queste piccole alterazioni sono spesso riscontrabili nei fluidi provenienti dalle cisti mammarie.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 16<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti mammaria.<\/strong><br \/>\nQuesto aggregato di cellule duttali benigne mostra lievi atipie con nucleoli visibili e lieve ingrandimento nucleare. Queste piccole alterazioni sono spesso riscontrabili nei fluidi provenienti dalle cisti mammarie.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1117.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1117.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 17<\/strong><\/p>\n<p>Agoaspirato mammario, cisti mammaria.<br \/>\nQuesto campo mostra un piccolo gruppo di cellule epiteliali benigne, una delle quali vacuolata e detriti cistici sul fondo.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 17<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti mammaria.<\/strong><br \/>\nQuesto campo mostra un piccolo gruppo di cellule epiteliali benigne, una delle quali vacuolata e detriti cistici sul fondo.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1118.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1118.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 18<\/strong><\/p>\n<p>Agoaspirato mammario, cisti mammaria.<br \/>\nLe cellule duttali benigne delle cisti possono presentare vacuolizzazione degenerativa, come in figura. Tali alterazioni non devono essere interpretate come diagnostiche di carcinoma.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 18<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti mammaria.<\/strong><br \/>\nLe cellule duttali benigne delle cisti possono presentare vacuolizzazione degenerativa, come in figura. Tali alterazioni non devono essere interpretate come diagnostiche di carcinoma.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1119.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1119.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 19<\/strong><\/p>\n<p>Agoaspirato mammario, metaplasia apocrina.<br \/>\nLe cellule apocrine benigne si presentano spesso in lembi piatti. Sono in genere presenti nei fluidi provenienti dalle cisti mammarie e negli agoaspirati eseguiti nelle aree con lesioni fibrocistiche.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 19<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, metaplasia apocrina.<\/strong><br \/>\nLe cellule apocrine benigne si presentano spesso in lembi piatti. Sono in genere presenti nei fluidi provenienti dalle cisti mammarie e negli agoaspirati eseguiti nelle aree con lesioni fibrocistiche.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1120.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1120.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 20<\/strong><\/p>\n<p>Agoaspirato mammario, metaplasia apocrina.<br \/>\nLe cellule apocrine presentano un abbondante citoplasma granulare e nuclei arrotondati con nucleoli prominenti. I bordi citoplasmatici sono di solito ben definiti.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 20<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, metaplasia apocrina.<\/strong><br \/>\nLe cellule apocrine presentano un abbondante citoplasma granulare e nuclei arrotondati con nucleoli prominenti. I bordi citoplasmatici sono di solito ben definiti.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1121.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1121.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 21: <\/strong> Agoaspirato mammario, lesione papillare cistica.<br \/>\nGli aspirati delle lesioni papillari cistiche contengono cellule epiteliali e macrofagi schiumosi. In questo gruppo, le cellule duttali benigne hanno dimensioni e forme uniformi e sono disposte a palizzata lungo uno dei bordi. Sopra al gruppo \u00e8 possibile notare un macrofago schiumoso ed una cellula duttale benigna. Se \u00e8 presente una lieve atipia cellulare, pu\u00f2 essere difficile distinguere una lesione benigna da una lesione papillare maligna.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 21<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, lesione papillare cistica.<\/strong><br \/>\nGli aspirati delle lesioni papillari cistiche contengono cellule epiteliali e macrofagi schiumosi. In questo gruppo, le cellule duttali benigne hanno dimensioni e forme uniformi e sono disposte a palizzata lungo uno dei bordi. Sopra al gruppo \u00e8 possibile notare un macrofago schiumoso ed una cellula duttale benigna. Se \u00e8 presente una lieve atipia cellulare, pu\u00f2 essere difficile distinguere una lesione benigna da una lesione papillare maligna.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1122.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1122.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 22<\/strong><\/p>\n<p>Agoaspirato mammario, lesione papillare cistica.<br \/>\nQuesto gruppo di cellule duttali benigne presenta un bordo arrotondato con disposizione a palizzata, che fa pensare a una struttura papillare, anche se non \u00e8 visibile alcun core fibrovascolare.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 22<br \/>\n<\/strong><br \/>\nAgoaspirato mammario, lesione papillare cistica.<br \/>\nQuesto gruppo di cellule duttali benigne presenta un bordo arrotondato con disposizione a palizzata, che fa pensare a una struttura papillare, anche se non \u00e8 visibile alcun core fibrovascolare.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1123.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1123.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 23: <\/strong> Agoaspirato mammario, lesione papillare cistica.<br \/>\nIn questo campo \u00e8 presente materiale secretivo e un aggregato papillare tondeggiante di cellule duttali vacuolate in degenerazione. \u00c8 opportuno classificare il campione come atipico perch\u00e9 non sempre \u00e8 possibile distinguere tra lesioni papillari benigne e maligne. La presenza di cellule apocrine \u00e8 spesso associata ad un un processo benigno.60x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 23<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, lesione papillare cistica.<\/strong><br \/>\nIn questo campo \u00e8 presente materiale secretivo e un aggregato papillare tondeggiante di cellule duttali vacuolate in degenerazione. \u00c8 opportuno classificare il campione come atipico perch\u00e9 non sempre \u00e8 possibile distinguere tra lesioni papillari benigne e maligne. La presenza di cellule apocrine \u00e8 spesso associata ad un un processo benigno.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1124.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1124.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 24<\/strong><\/p>\n<p>Agoaspirato mammario, lesione papillare cistica.<br \/>\nI macrofagi schiumosi, come quelli in foto , sono presenti sia nelle lesioni cistiche benigne che in quelle maligne, a prescindere dalla natura papillare.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 24<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, lesione papillare cistica.<\/strong><br \/>\nI macrofagi schiumosi, come quelli in foto , sono presenti sia nelle lesioni cistiche benigne che in quelle maligne, a prescindere dalla natura papillare.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1125.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1125.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 25: <\/strong> Agoaspirato mammario, sferulosi collagena.<br \/>\nSi tratta di una lesione benigna che viene in genere individuata casualmente durante le biopsie mammarie . Genera di rado una massa palpabile. L&#8217;aspirato contiene tracce di iperplasia duttale benigna, cellule duttali e cellule apocrine metaplastiche benigne, cellule mioepiteliali e globuli di materiale extracellulare circondato da piccole cellule epiteliali benigne. Un quadro simile \u00e8 riscontrabile negli aspirati del carcinoma mammario adenoideo cistico.60x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 25<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, sferulosi collagena.<\/strong><br \/>\nSi tratta di una lesione benigna che viene in genere individuata casualmente durante le biopsie mammarie . Genera di rado una massa palpabile. L&#8217;aspirato contiene tracce di iperplasia duttale benigna, cellule duttali e cellule apocrine metaplastiche benigne, cellule mioepiteliali e globuli di materiale extracellulare circondato da piccole cellule epiteliali benigne. Un quadro simile \u00e8 riscontrabile negli aspirati del carcinoma mammario adenoideo cistico.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1126.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1126.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 26<\/strong><\/p>\n<p>Agoaspirato mammario, sferulosi collagena.<br \/>\nQuesto grande globulo di materiale ialino \u00e8 circondato da piccole cellule epiteliali.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 26<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, sferulosi collagena.<\/strong><br \/>\nQuesto grande globulo di materiale ialino \u00e8 circondato da piccole cellule epiteliali.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1127.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1127.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 27<\/strong><\/p>\n<p>Agoaspirato mammario, sferulosi collagena\/metaplasia apocrina.<br \/>\nNell&#8217;aspirato del caso di sferulosi collagena presentato in precedenza \u00e8 visibile un lembo di cellule apocrine metaplastiche con citoplasma relativamente abbondante.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 27<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, sferulosi collagena\/metaplasia apocrina.<\/strong><br \/>\nNell&#8217;aspirato del caso di sferulosi collagena presentato in precedenza \u00e8 visibile un lembo di cellule apocrine metaplastiche con citoplasma relativamente abbondante.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1128.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1128.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 28: <\/strong> Agoaspirato mammario, carcinoma duttale in situ.<br \/>\nSi tratta di un aspirato cellulare che presenta aggregati di cellule tumorali, cellule maligne singole e macrofagi schiumosi. In presenza di un carcinoma duttale in situ (DCIS) sono spesso presenti cellule mioepiteliali che ricoprono gli aggregati di cellule maligne. Come nei tumori invasivi, le cellule tumorali tendono ad aggregarsi piuttosto che ad apparire isolate. Inoltre, al DCIS non sono associate strutture tubulari. Il DCIS comedonico \u00e8 in genere associato a necrosi e calcio.40x<\/div>\n<\/div>\n<div class=\"chartColumnxLongCell\"><strong>Figura 28<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale in situ.<\/strong><br \/>\nSi tratta di un aspirato cellulare che presenta aggregati di cellule tumorali, cellule maligne singole e macrofagi schiumosi. In presenza di un carcinoma duttale in situ (DCIS) sono spesso presenti cellule mioepiteliali che ricoprono gli aggregati di cellule maligne. Come nei tumori invasivi, le cellule tumorali tendono ad aggregarsi piuttosto che ad apparire isolate. Inoltre, al DCIS non sono associate strutture tubulari. Il DCIS comedonico \u00e8 in genere associato a necrosi e calcio.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1129.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1129.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 29<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale in situ.<br \/>\n\u00c8 possibile notare aggregati di cellule tumorali piuttosto regolari. Nel gruppo di cellule sulla destra si ha l&#8217;impressione di rilevare un core fibrovascolare.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 29<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale in situ.<\/strong><br \/>\n\u00c8 possibile notare aggregati di cellule tumorali piuttosto regolari. Nel gruppo di cellule sulla destra si ha l&#8217;impressione di rilevare un core fibrovascolare.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1130.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1130.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 30<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nQuesto campo osservato a piccolo ingrandimento contiene abbondante necrosi cellulare e un aggregato compatto al centro di cellule da carcinoma duttale invasivo.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 30<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nQuesto campo osservato a piccolo ingrandimento contiene abbondante necrosi cellulare e un aggregato compatto al centro di cellule da carcinoma duttale invasivo.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1131.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1131.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 31<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nUn ingrandimento maggiore consente di rilevare l&#8217;affollamento di cellule neoplastiche e i nucleoli prominenti. La cromatina \u00e8 anormale e sbiadita.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 31<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nUn ingrandimento maggiore consente di rilevare l&#8217;affollamento di cellule neoplastiche e i nucleoli prominenti. La cromatina \u00e8 anormale e sbiadita.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1132.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1132.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 32<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nLe cellule tumorali di questo campo mostrano dissociazione, pleomorfismo, irregolarit\u00e0 nucleare, ipercromasia e nucleoli.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 32<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nLe cellule tumorali di questo campo mostrano dissociazione, pleomorfismo, irregolarit\u00e0 nucleare, ipercromasia e nucleoli.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1133.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1133.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 33<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nIn questa immagine sono visibili necrosi, &#8220;cannibalismo&#8221; di cellule tumorali e dissociazione cellulare.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 33<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nIn questa immagine sono visibili necrosi, &#8220;cannibalismo&#8221; di cellule tumorali e dissociazione cellulare.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1134.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1134.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 34<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, basso grado.<br \/>\nIn questo caso, le cellule del carcinoma si presentano sia aggregate che singole, associate a particelle di calcio, che assumono una colorazione rossa con la colorazione Papanicolaou. Le cellule monomorfe, con margini nucleari regolari e micronucleoli e sono suggestive di carcinoma duttale di basso grado.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 34<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, basso grado.<\/strong><br \/>\nIn questo caso, le cellule del carcinoma si presentano sia aggregate che singole, associate a particelle di calcio, che assumono una colorazione rossa con la colorazione Papanicolaou. Le cellule monomorfe, con margini nucleari regolari e micronucleoli e sono suggestive di carcinoma duttale di basso grado.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1135.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1135.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 35<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, basso grado.<br \/>\nIn questo campo sono presenti numerose cellule carcinomatose singole. I nuclei sono sbiaditi, ma il pattern della cromatina \u00e8 chiaramente anormale. In questo caso, i nucleoli non sono ingranditi.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 35<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, basso grado.<\/strong><br \/>\nIn questo campo sono presenti numerose cellule carcinomatose singole. I nuclei sono sbiaditi, ma il pattern della cromatina \u00e8 chiaramente anormale. In questo caso, i nucleoli non sono ingranditi.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1136.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1136.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 36<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, basso grado.<br \/>\nSi tratta di un esempio di carcinoma duttale di basso grado. Alcune cellule tumorali sono reunite in un aggregatocomaptto , altre sono isolate. \u00c8 possibile notare i margini nucleari arrotondati.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 36<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, basso grado.<\/strong><br \/>\nSi tratta di un esempio di carcinoma duttale di basso grado. Alcune cellule tumorali sono reunite in un aggregatocomaptto , altre sono isolate. \u00c8 possibile notare i margini nucleari arrotondati.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1137.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1137.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 37<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nQuesto campo mostra cellule tumorali isolate e in piccoli aggregati. Alcune cellule sembrano contenere vacuoli intracitoplasmatici. La dimensione dei nuclei negli aggregati cellulari \u00e8 variabile.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 37<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nQuesto campo mostra cellule tumorali isolate e in piccoli aggregati. Alcune cellule sembrano contenere vacuoli intracitoplasmatici. La dimensione dei nuclei negli aggregati cellulari \u00e8 variabile.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1138.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1138.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 38<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale.<br \/>\nQueste cellule maligne presentano vacuoli intracitoplasmatici ben definiti, alcuni dei quali hanno aspetto targetoide. Sebbene questa caratteristica venga in genere descritta nei carcinoma lobulare, pu\u00f2 essere associata anche a un carcinoma duttale. 60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 38<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale.<\/strong><br \/>\nQueste cellule maligne presentano vacuoli intracitoplasmatici ben definiti, alcuni dei quali hanno aspetto targetoide. Sebbene questa caratteristica venga in genere descritta nei carcinoma lobulare, pu\u00f2 essere associata anche a un carcinoma duttale.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1139.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1139.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 39<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, grado 2.<br \/>\nSono visibili aggregati di cellule maligne vacuolate, con nuclei rotondi e nucleoli prominenti. Notare la necrosi sul fondo.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 39<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, grado 2.<\/strong><br \/>\nSono visibili aggregati di cellule maligne vacuolate, con nuclei rotondi e nucleoli prominenti. Notare la necrosi sul fondo.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1140.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1140.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 40<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, grado 2.<br \/>\nSi tratta dello stesso caso presentato nella figura 39. Le cellule tumorali presentano un&#8217;evidente variabilit\u00e0 nella dimensione di nuclei e nucleoli. E\u2019 presente necrosi. La biopsia ha dato esito di carcinoma duttale moderatamente differenziato.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 40<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, grado 2.<\/strong><br \/>\nSi tratta dello stesso caso presentato nella figura 39. Le cellule tumorali presentano un&#8217;evidente variabilit\u00e0 nella dimensione di nuclei e nucleoli. E\u2019 presente necrosi. La biopsia ha dato esito di carcinoma duttale moderatamente differenziato.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1141.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1141.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 41<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nQuesto campo mostra la variabilit\u00e0 nella dimensione dei nuclei tipica del carcinoma duttale. Alcuni nuclei sono quasi fusiformi. La maggior parte di essi appare pi\u00f9 grande dei neutrofili e dei linfociti presenti nelle vicinanze. Il pattern della cromatina mostra addensamenti e chiarificazioni. 60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 41<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nQuesto campo mostra la variabilit\u00e0 nella dimensione dei nuclei tipica del carcinoma duttale. Alcuni nuclei sono quasi fusiformi. La maggior parte di essi appare pi\u00f9 grande dei neutrofili e dei linfociti presenti nelle vicinanze. Il pattern della cromatina mostra addensamenti e chiarificazioni. 60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1142.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1142.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 42<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nSi tratta di un altro esempio di pleomorfismo in un caso di carcinoma duttale. Questo aggregato di cellule tumorali contiene nuclei di dimensioni variabili. Alcune cellule hanno grandi nucleoli multipli. Sul fondo \u00e8 presente necrosi.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 42<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nSi tratta di un altro esempio di pleomorfismo in un caso di carcinoma duttale. Questo aggregato di cellule tumorali contiene nuclei di dimensioni variabili. Alcune cellule hanno grandi nucleoli multipli. Sul fondo \u00e8 presente necrosi.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1143.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1143.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 43<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nLe cellule maligne di questo campo sono multinucleate, con nuclei sbiaditi che presentano cromatina addensata e chiarificata.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 43<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nLe cellule maligne di questo campo sono multinucleate, con nuclei sbiaditi che presentano cromatina addensata e chiarificata.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1144.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1144.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 44<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nSi tratta dello stesso caso presentato nella figura 43. Si nota una cellula binucleata con nuclei ipercromici e cromatina addensata e chiarificata.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 44<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nSi tratta dello stesso caso presentato nella figura 43. Si nota una cellula binucleata con nuclei ipercromici e cromatina addensata e chiarificata.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1145.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1145.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 45<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nSi tratta di un esempio di carcinoma duttale di alto grado scarsamente differenziato. Le cellule sono isolate con cromatina anormale e nucleoli \u00e8 presente necrosi cellulare sul fondo.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 45<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nSi tratta di un esempio di carcinoma duttale di alto grado scarsamente differenziato. Le cellule sono isolate con cromatina anormale e nucleoli \u00e8 presente necrosi cellulare sul fondo.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1146.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1146.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 46<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma duttale, alto grado.<br \/>\nQuesto campione appartenente allo stesso caso presentato nella figura 45 consente di osservare l&#8217;evidente addensamento e chiarificazione della cromatina di questa cellula maligna.60X<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 46<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma duttale, alto grado.<\/strong><br \/>\nQuesto campione appartenente allo stesso caso presentato nella figura 45 consente di osservare l&#8217;evidente addensamento e chiarificazione della cromatina di questa cellula maligna.60X<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1147.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1147.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 47<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma lobulare.<br \/>\nGli agoaspirati del carcinoma lobulare tendono a contenere poche cellule, ma talvolta vi sono delle eccezioni, come in questo esempio. Le cellule tumorali sono disposte singolarmente, ma possono costituire piccoli aggregati, disposte in fila singola.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 47<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma lobulare.<\/strong><br \/>\nGli agoaspirati del carcinoma lobulare tendono a contenere poche cellule, ma talvolta vi sono delle eccezioni, come in questo esempio. Le cellule tumorali sono disposte singolarmente, ma possono costituire piccoli aggregati, disposte in fila singola.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1148.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1148.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 48<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma lobulare.<br \/>\nLe cellule neoplastiche sono di solito piccole, con margini nucleari tondi o irregolari e nuclei eccentrici che conferiscono un aspetto plasmocitoide, come in questa foto.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 48<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma lobulare.<\/strong><br \/>\nLe cellule neoplastiche sono di solito piccole, con margini nucleari tondi o irregolari e nuclei eccentrici che conferiscono un aspetto plasmocitoide, come in questa foto.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1149.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1149.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 49<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma lobulare.<br \/>\nSono visibili cellule dall&#8217;aspetto plasmocitoide e dai nuclei tondi. Il materiale sul fondo sembra essere di natura proteica, piuttosto che necrotico. Una piccola fila singola di 3 cellule \u00e8 visibile al centro del campo.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 49<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma lobulare.<\/strong><br \/>\nSono visibili cellule dall&#8217;aspetto plasmocitoide e dai nuclei tondi. Il materiale sul fondo sembra essere di natura proteica, piuttosto che necrotico. Una piccola fila singola di 3 cellule \u00e8 visibile al centro del campo.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1150.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1150.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 50<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma lobulare.<br \/>\nNegli aspirati del carcinoma lobulare sono in genere visibili vacuoli intracitoplasmatici, come ad esempio quelli della cellula singola situata nella parte superiore sinistra dell\u2019 immagine. I vacuoli non sono una caratteristica esclusiva del carcinoma lobulare; sono riscontrabili anche nel carcinoma duttale.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 50<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma lobulare.<\/strong><br \/>\nNegli aspirati del carcinoma lobulare sono in genere visibili vacuoli intracitoplasmatici, come ad esempio quelli della cellula singola situata nella parte superiore sinistra dell\u2019 immagine. I vacuoli non sono una caratteristica esclusiva del carcinoma lobulare; sono riscontrabili anche nel carcinoma duttale.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1151.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1151.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 51<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma lobulare.<br \/>\nI nucleoli, anche se non costituiscono una caratteristica frequente del carcinoma lobulare (ad eccezione del carcinoma lobulare pleomorfico), possono talvolta essere presenti.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 51<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma lobulare.<\/strong><br \/>\nI nucleoli, anche se non costituiscono una caratteristica frequente del carcinoma lobulare (ad eccezione del carcinoma lobulare pleomorfico), possono talvolta essere presenti.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1152.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1152.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 52<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma colloide (mucinoso).<br \/>\nPiccole cellule singole e in aggregati sono visibili su un fondo di mucina. \u00c8 preferibile classificare casi del genere come carcinomi duttali con differenziazione mucinosa piuttosto che come carcinomi colloidi o mucinosi perch\u00e9 la diagnosi dipende dal fatto che tutto il tumore produca mucina o meno.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 52<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma colloide (mucinoso).<\/strong><br \/>\nPiccole cellule singole e in aggregati sono visibili su un fondo di mucina. \u00c8 preferibile classificare casi del genere come carcinomi duttali con differenziazione mucinosa piuttosto che come carcinomi colloidi o mucinosi perch\u00e9 la diagnosi dipende dal fatto che tutto il tumore produca mucina o meno.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1153.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1153.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 53<\/strong><\/p>\n<p><strong> Agoaspirato mammario, carcinoma colloide.<\/strong><br \/>\nLe cellule maligne di questa lesione sono regolari, con margini nucleari omogenei, cromatina uniformemente distribuita e assenza di nucleoli. Se nelle cellule non fosse visibile la mucina, potrebbero essere confuse con cellule benigne.60x<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 53<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma colloide.<\/strong>.<br \/>\nLe cellule maligne di questa lesione sono regolari, con margini nucleari omogenei, cromatina uniformemente distribuita e assenza di nucleoli. Se nelle cellule non fosse visibile la mucina, potrebbero essere confuse con cellule benigne.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1154.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1154.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 54<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma midollare.<br \/>\nGli agoaspirati di questi tumori contengono solitamente aggregati di grandi cellule tumorali pleomorfe con nucleoli prominenti e linfociti, come mostrato in figura. \u00c8 possibile notare anche la presenza di plasmacellule.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 54<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma midollare.<\/strong><br \/>\nGli agoaspirati di questi tumori contengono solitamente aggregati di grandi cellule tumorali pleomorfe con nucleoli prominenti e linfociti, come mostrato in figura. \u00c8 possibile notare anche la presenza di plasmacellule.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1155.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1155.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 55<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma midollare.<br \/>\nQuesto aggregato di cellule presenta grandi nucleoli centrali e cromatina anormale. Sono visibili anche alcuni linfociti.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 55<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma midollare.<\/strong><br \/>\nQuesto aggregato di cellule presenta grandi nucleoli centrali e cromatina anormale. Sono visibili anche alcuni linfociti.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1156.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1156.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 56<\/strong><\/p>\n<p><strong> Agoaspirato mammario, carcinoma adenoideo cistico.<\/strong><br \/>\nQuesti tumori contengono solitamente materiale ialino extracellulare in forme globulari o cilindriche\/tubulari, circondato da cellule piccole, regolari e neoplastiche. In questo campo sono presenti due strutture globulari adiacenti.60x<\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 56<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma adenoideo cistico.<\/strong><br \/>\nQuesti tumori contengono solitamente materiale ialino extracellulare in forme globulari o cilindriche\/tubulari, circondato da cellule piccole, regolari e neoplastiche. In questo campo sono presenti due strutture globulari adiacenti.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1157.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1157.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 57<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma adenoideo cistico.<br \/>\nIn questo caso, \u00e8 possibile osservare materiale ialino extracellulare che forma un tubulo indistinto con due strutture globulari attaccate.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 57<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma adenoideo cistico.<\/strong><br \/>\nIn questo caso, \u00e8 possibile osservare materiale ialino extracellulare che forma un tubulo indistinto con due strutture globulari attaccate.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1158.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1158.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 58<\/strong><\/p>\n<p>Agoaspirato mammario, carcinoma adenoideo cistico.<br \/>\nQuesto campo mostra una raccolta di globuli ialini ricoperti da piccole cellule tumorali. La diagnosi differenziale \u00e8 quella di sferulosi collagena, una lesione benigna in cui i globuli ialini sono associati a cellule duttali benigne o iperplastiche. 60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 58<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, carcinoma adenoideo cistico.<\/strong><br \/>\nQuesto campo mostra una raccolta di globuli ialini ricoperti da piccole cellule tumorali. La diagnosi differenziale \u00e8 quella di sferulosi collagena, una lesione benigna in cui i globuli ialini sono associati a cellule duttali benigne o iperplastiche.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1159.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1159.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 59<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nNon tutte le cisti sono di natura benigna. Alcuni carcinomi duttali possono presentarsi sotto forma di lesioni cistiche come in questo esempio. L\u2019immagine a piccolo ingrandimento mostra la presenza di materiale proteico, sangue e un aggregato di cellule ipercromiche.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 59<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nNon tutte le cisti sono di natura benigna. Alcuni carcinomi duttali possono presentarsi sotto forma di lesioni cistiche come in questo esempio. L\u2019immagine a piccolo ingrandimento mostra la presenza di materiale proteico, sangue e un aggregato di cellule ipercromiche.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1160.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1160.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 60<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nAd alta risoluzione, l&#8217;aggregato di cellule mostrato nella figura 59 mostra pleomorfismo, nucleoli visibili e vacuolizzazione. La biopsia ha dato esito di carcinoma duttale.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 60<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nAd alta risoluzione, l&#8217;aggregato di cellule mostrato nella figura 59 mostra pleomorfismo, nucleoli visibili e vacuolizzazione. La biopsia ha dato esito di carcinoma duttale.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1161.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1161.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 61<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nSi tratta di un altro esempio di carcinoma duttale diagnosticato grazie all\u2019agoaspirazione di una cisti. Questo campo contiene cellule maligne vacuolate ed evidentemente pleomorfe con nucleoli e cromatina anormale.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 61<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nSi tratta di un altro esempio di carcinoma duttale diagnosticato grazie all\u2019agoaspirazione di una cisti. Questo campo contiene cellule maligne vacuolate ed evidentemente pleomorfe con nucleoli e cromatina anormale.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1162.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1162.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 62<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nQuesto campo mostra un aggregato ipercromico di cellule epiteliali con numerosi detriti cellulari sul fondo, che suggeriscono una diagnosi di carcinoma.20x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 62<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nQuesto campo mostra un aggregato ipercromico di cellule epiteliali con numerosi detriti cellulari sul fondo, che suggeriscono una diagnosi di carcinoma.20x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1163.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1163.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 63<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nUn piccolo gruppo di cellule tumorali con nucleoli prominenti e margini nucleari piuttosto regolari. \u00c8 possibile notare la necrosi circostante.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 63<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nUn piccolo gruppo di cellule tumorali con nucleoli prominenti e margini nucleari piuttosto regolari. \u00c8 possibile notare la necrosi circostante.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1164.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1164.jpg\" alt=\"Image 3\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 64<\/strong><\/p>\n<p>Agoaspirato mammario, cisti maligna.<br \/>\nSi tratta dello stesso caso presentato nella figura 63. Le cellule sono sovrapposte, ma mostrano anche un principio di dissociazione, margini nucleari irregolari, cromatina anormale e nucleoli visibili.60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 64<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, cisti maligna.<\/strong><br \/>\nSi tratta dello stesso caso presentato nella figura 63. Le cellule sono sovrapposte, ma mostrano anche un principio di dissociazione, margini nucleari irregolari, cromatina anormale e nucleoli visibili.60x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1165.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1165.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 65<\/strong><\/p>\n<p>Agoaspirato mammario, linfoma.<br \/>\nQuesto campo mostra cellule sparse con citoplasma quasi assente. Non sono presenti aggregati. Le cellule hanno nuclei tondi con una rima citoplasmatica da un lato. Le caratteristiche sembrano essere pi\u00f9 linfoidi pi\u00f9 che epiteliali.40x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 65<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, linfoma.<\/strong><br \/>\nQuesto campo mostra cellule sparse con citoplasma quasi assente. Non sono presenti aggregati. Le cellule hanno nuclei tondi con una rima citoplasmatica da un lato. Le caratteristiche sembrano essere pi\u00f9 linfoidi pi\u00f9 che epiteliali.40x<\/div>\n<div class=\"newRow\"><\/div>\n<div class=\"chartColumnCell\"><a class=\"highslide\" href=\"\/gallery\/images_large\/slide1166.jpg\"><br \/>\n<img decoding=\"async\" title=\"Click to enlarge\" src=\"\/gallery\/images\/slide1166.jpg\" alt=\"Image 2\" border=\"0\" \/><\/a><\/p>\n<div class=\"highslide-caption\"><strong>Figura 66<\/strong><\/p>\n<p>Agoaspirato mammario, linfoma.<br \/>\nUn ingrandimento maggiore consente di determinare la natura linfoide delle cellule, che presentano un pattern della cromatina caratteristico. La diagnosi pu\u00f2 essere confermata grazie alla colorazione immunocitochimica con LCA ( antigene leucocitario ) di un vetrino ThinPrep non colorato in precedenza. 60x<\/p><\/div>\n<\/div>\n<div class=\"chartColumnLongCell\"><strong>Figura 66<br \/>\n<\/strong><br \/>\n<strong> Agoaspirato mammario, linfoma.<\/strong><br \/>\nUn ingrandimento maggiore consente di determinare la natura linfoide delle cellule, che presentano un pattern della cromatina caratteristico. La diagnosi pu\u00f2 essere confermata grazie alla colorazione immunocitochimica con LCA ( antigene leucocitario ) di un vetrino ThinPrep non colorato in precedenza. 60x<\/div>\n<\/div>\n<div class=\"newRow\"><\/div>\n<p><a class=\"back\" href=\"#\">Torna a inizio pagina<\/a><\/p>\n<p><a href=\"nongyn_atlas.htm\">Ritorna alla Indice dei contenuti<\/a><\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_widget_sidebar sidebar_id=&#8221;consulting-right-sidebar&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_raw_html 0=&#8221;&#8221;]JTNDY2VudGVyJTNFJTNDYSUyMGNsYXNzJTNEJTIyc2hpZnRuYXYtdG9nZ2xlJTIwc2hpZnRuYXYtdG9nZ2xlLWJ1dHRvbiUyMiUyMGRhdGEtc2hpZnRuYXYtdGFyZ2V0JTNEJTIyc2hpZnRuYXYtbWFpbiUyMiUzRSUzQ2klMjBjbGFzcyUzRCUyMmZhJTIwZmEtYmFycyUyMiUzRSUzQyUyRmklM0UlMjBUYWJsZSUyMG9mJTIwQ29udGVudHMlMjAlM0MlMkZhJTNFJTNDJTJGY2VudGVyJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_custom_heading text=&#8221;itologia degli aspirati con ago sottile &#8211; MAMMELLA&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text] MAMMELLA Grace T. McKee, medico Introduzione La mammella \u00e8 costituita da adipe e stroma che supportano il tessuto ghiandolare, un sistema duttale con diramazioni collegate a 6-10 dotti principali che sboccano nel capezzolo. Nella mammella possono svilupparsi lesioni<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":1951,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2016","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/pages\/2016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":0,"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/pages\/2016\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/pages\/1951"}],"wp:attachment":[{"href":"https:\/\/stage.cytologystuff.com\/it\/wp-json\/wp\/v2\/media?parent=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}