{"id":11324,"date":"2017-08-01T13:43:36","date_gmt":"2017-08-01T13:43:36","guid":{"rendered":"https:\/\/cytologystuff1.wpengine.com\/cellient-atlas-table-of-contents\/"},"modified":"2018-04-02T11:17:52","modified_gmt":"2018-04-02T11:17:52","slug":"cellient-atlas-table-of-contents","status":"publish","type":"page","link":"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/","title":{"rendered":"Cellient Atlas &#8211; Table of Contents"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221;][vc_custom_heading text=&#8221;Inhoudsopgave Cellient\u00ae Atlas&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1501004719015{margin-bottom: 25px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_tta_accordion color=&#8221;sky&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;BORST FNA&#8221; tab_id=&#8221;1501004541917-ea783388-8054d27f-7592&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/\">Inleiding<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec2\">Benigne<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec3\">Normale ductale hyperplasie<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec4\">Atypische ductale hyperplasie<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec5\">Papiloom<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec6\">Papillair carcinoom<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec7\">Fibroadenoom<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/\">Phyllodes tumor<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec9\">Ductaal carcinoom<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-breast-fna\/#sec10\">Lobulair carcinoom<\/a><\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Thyroid FNA&#8221; tab_id=&#8221;1501004546764-461e918e-6b7ed27f-7592&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/\">Inleiding<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Benigne<\/span>\n<ul class=\"sublist\">\n<li><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/#sec2\">Hyperplastisch.adenomato\u00efde nodule<\/a><\/li>\n<li><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/#sec3\">Lymfocytische thyro\u00efditis<\/a><\/li>\n<\/ul>\n<\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/#sec4\">Folliculair neoplasma<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/#sec5\">Papillair schildkliercarcinoom<\/a><\/span><\/li>\n<li><span style=\"font-size: 14pt;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/stage.cytologystuff.com\/nl\/cellient-atlas-table-of-contents\/cellient-atlas-thyroid-fna\/#sec6\">Medullair carcinoom<\/a><\/span><\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;11017&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row 0=&#8221;&#8221;][vc_column 0=&#8221;&#8221;][vc_custom_heading text=&#8221;Inhoudsopgave Cellient\u00ae Atlas&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1501004719015{margin-bottom: 25px !important;}&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_tta_accordion color=&#8221;sky&#8221; active_section=&#8221;1&#8243; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;BORST FNA&#8221; tab_id=&#8221;1501004541917-ea783388-8054d27f-7592&#8243;][vc_row_inner][vc_column_inner][vc_column_text] Inleiding Benigne Normale ductale hyperplasie Atypische ductale hyperplasie Papiloom Papillair carcinoom Fibroadenoom Phyllodes tumor Ductaal carcinoom Lobulair carcinoom [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Thyroid FNA&#8221; tab_id=&#8221;1501004546764-461e918e-6b7ed27f-7592&#8243;][vc_row_inner][vc_column_inner][vc_column_text] Inleiding Benigne Hyperplastisch.adenomato\u00efde nodule Lymfocytische thyro\u00efditis Folliculair neoplasma Papillair schildkliercarcinoom Medullair carcinoom [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;11017&#8243;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-11324","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/pages\/11324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/comments?post=11324"}],"version-history":[{"count":0,"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/pages\/11324\/revisions"}],"wp:attachment":[{"href":"https:\/\/stage.cytologystuff.com\/nl\/wp-json\/wp\/v2\/media?parent=11324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}